{"id":129108,"date":"2026-03-12T03:40:00","date_gmt":"2026-03-12T10:40:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=129108"},"modified":"2026-03-11T16:58:15","modified_gmt":"2026-03-11T23:58:15","slug":"un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/","title":{"rendered":"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO"},"content":{"rendered":"\n<p><strong><em>Esto sabemos sobre el hombre que ha causado revuelo debido al aspecto que posee de aquella &#8220;eterna juventud&#8221;.<\/em><\/strong><\/p>\n\n\n\n<p>La figura de Chuando Tan es probablemente uno de los fen\u00f3menos que m\u00e1s revuelo ha causado entre la audiencia por su aspecto f\u00edsico y la edad que tiene.<\/p>\n\n\n\n<p>\u00c9l naci\u00f3 en Singapur, en el a\u00f1o de1966, pero parece haber negociado un contrato peculiar con el tiempo -al estilo Dorian Gray o Entrevista con el Vampiro- porque para \u00e9l la biolog\u00eda parece no tener efecto<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 se sabe sobre Chuando Tan?<\/strong><br>Al ver sus fotograf\u00edas es inevitable pensar que nos encontramos ante un hombre que llegado a los 60 a\u00f1os, es decir, ha superado la sexta d\u00e9cada de vida pero su imagen desaf\u00eda las expectativas biol\u00f3gicas tradicionales, proyectando una vitalidad que suele asociarse a individuos mucho m\u00e1s j\u00f3venes.<\/p>\n\n\n\n<p>Es aspecto de Tan no es un accidente, sino el resultado de una serie de acciones disciplinarias. Dicho hombre inici\u00f3&nbsp;tiempo atr\u00e1s (por el a\u00f1o 2017) en el mundo de la moda siendo modelo, tal experiencia le otorg\u00f3 una comprensi\u00f3n profunda de la est\u00e9tica.&nbsp;<\/p>\n\n\n\n<p>M\u00e1s tarde explor\u00f3 brevemente otras actividades, pero fue en la industria de la moda, integr\u00e1ndose nuevamente a \u00e9ste mundo, que se vio &#8216;cara a cara&#8217; con su verdadera vocaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Durante a\u00f1os Tan se mantuvo bajo el anonimato hasta que casi por accidente el mundo termin\u00f3 volviendo la c\u00e1mara hacia \u00e9l debido a esa tersa piel y ese fresco semblante que le caracteriza.<\/p>\n\n\n\n<p>El fen\u00f3meno de su &#8220;eterna juventud&#8221; no solo es un tema de curiosidad cient\u00edfica o vanidad; ha generado un impacto sumamente importante entre las audiencias.&nbsp;<\/p>\n\n\n\n<p>En un mundo obsesionado con los halagos inmediatos y los filtros de las redes sociales que alteran la realidad, la imagen de Tan es un caso de estudio sobre la disciplina del auto cuidado desde la consciencia.<\/p>\n\n\n\n<p>Su popularidad no radica realmente en el uso de herramientas de edici\u00f3n de \u00faltima generaci\u00f3n, como muchos fot\u00f3grafos lo hacen en sus obras, sino en una minuciosa rutina de tres pasos que ha seguido por a\u00f1os.<\/p>\n\n\n\n<p>Una dieta donde la prote\u00edna limpia y los nutrientes esenciales no son negociables.<br>El entrenamiento de fuerza como eje central para mantener la masa muscular y la tasa metab\u00f3lica.<\/p>\n\n\n\n<p>Un respeto absoluto por sus horas de sue\u00f1o, esto algo que \u00e9l ha se\u00f1alado repetidamente como la pieza m\u00e1s infravalorada del rompecabezas.<\/p>\n\n\n\n<p>Este impacto genera un resultado interesante porque mientras algunos ven en \u00e9l un modelo de aspiraci\u00f3n est\u00e9tica, otros lo utilizan como un recordatorio de que el envejecimiento puede ser un proceso que, con disciplina, podemos &#8220;combatir&#8221;.\u00a0<\/p>\n\n\n\n<p>Sin embargo, el propio Tan ha manejado su fama con una tranquilidad bastante refrescante. A pesar del escrutinio p\u00fablico, \u00e9l mantiene que no busca la inmortalidad, sino simplemente habitar su cuerpo de la manera m\u00e1s eficiente posible.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"618\" height=\"302\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/image.png\" alt=\"\" class=\"wp-image-129110\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/image.png 618w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/image-300x147.png 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/image-600x293.png 600w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/image-533x261.png 533w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/><\/figure>\n\n\n\n<p><strong>El vampiro de Singapur y su lecci\u00f3n al mundo<\/strong><br>M\u00e1s all\u00e1 de su apariencia, lo m\u00e1s rescatable de la historia de Chuando Tan es su capacidad para mantenerse fiel a su estilo de vida a pesar del ruido medi\u00e1tico que genera ver a un hombre de la tercera edad pareciendo un jovencito.\u00a0<\/p>\n\n\n\n<p>En una sociedad donde la salud se percibe a menudo como una meta externa y vol\u00e1til, \u00e9l representa la idea de que la longevidad es, ante todo, un proyecto de consistencia diaria m\u00e1s all\u00e1 del aspecto f\u00edsico.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esto sabemos sobre el hombre que ha causado revuelo debido al aspecto que posee de aquella &#8220;eterna juventud&#8221;. La figura de Chuando Tan es probablemente uno de los fen\u00f3menos que m\u00e1s revuelo ha causado entre la audiencia por su aspecto f\u00edsico y la edad que tiene. \u00c9l naci\u00f3 en Singapur, en el a\u00f1o de1966, pero [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":129109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-129108","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-las-asombrosas"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Esto sabemos sobre el hombre que ha causado revuelo debido al aspecto que posee de aquella &#8220;eterna juventud&#8221;. La figura de Chuando Tan es probablemente uno de los fen\u00f3menos que m\u00e1s revuelo ha causado entre la audiencia por su aspecto f\u00edsico y la edad que tiene. \u00c9l naci\u00f3 en Singapur, en el a\u00f1o de1966, pero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-12T10:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/chuando-tan-el-modelo-que.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milenio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milenio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/\"},\"author\":{\"name\":\"Milenio\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/47ec0135738f4b0c7495f06a77a2c976\"},\"headline\":\"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO\",\"datePublished\":\"2026-03-12T10:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/\"},\"wordCount\":613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/chuando-tan-el-modelo-que.jpg\",\"articleSection\":[\"LAS ASOMBROSAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/\",\"name\":\"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/chuando-tan-el-modelo-que.jpg\",\"datePublished\":\"2026-03-12T10:40:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/chuando-tan-el-modelo-que.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/chuando-tan-el-modelo-que.jpg\",\"width\":500,\"height\":282},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/03\\\/12\\\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/47ec0135738f4b0c7495f06a77a2c976\",\"name\":\"Milenio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"caption\":\"Milenio\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/milenio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO - Fuentes Fidedignas","og_description":"Esto sabemos sobre el hombre que ha causado revuelo debido al aspecto que posee de aquella &#8220;eterna juventud&#8221;. La figura de Chuando Tan es probablemente uno de los fen\u00f3menos que m\u00e1s revuelo ha causado entre la audiencia por su aspecto f\u00edsico y la edad que tiene. \u00c9l naci\u00f3 en Singapur, en el a\u00f1o de1966, pero [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-03-12T10:40:00+00:00","og_image":[{"width":500,"height":282,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/chuando-tan-el-modelo-que.jpg","type":"image\/jpeg"}],"author":"Milenio","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Milenio","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/"},"author":{"name":"Milenio","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/47ec0135738f4b0c7495f06a77a2c976"},"headline":"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO","datePublished":"2026-03-12T10:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/"},"wordCount":613,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/chuando-tan-el-modelo-que.jpg","articleSection":["LAS ASOMBROSAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/","name":"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/chuando-tan-el-modelo-que.jpg","datePublished":"2026-03-12T10:40:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/chuando-tan-el-modelo-que.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/03\/chuando-tan-el-modelo-que.jpg","width":500,"height":282},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/03\/12\/un-vampiro-hombre-en-singapur-cumple-60-anos-pero-parece-un-joven-de-30-asi-luce-foto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"\u00bfUn vampiro? Hombre en Singapur cumple 60 a\u00f1os, pero parece un joven de 30; as\u00ed luce | FOTO"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/47ec0135738f4b0c7495f06a77a2c976","name":"Milenio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","caption":"Milenio"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/milenio\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/129108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=129108"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/129108\/revisions"}],"predecessor-version":[{"id":129111,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/129108\/revisions\/129111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/129109"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=129108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=129108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=129108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}