{"id":127269,"date":"2026-02-13T17:25:33","date_gmt":"2026-02-14T00:25:33","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=127269"},"modified":"2026-02-13T17:25:40","modified_gmt":"2026-02-14T00:25:40","slug":"historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/","title":{"rendered":"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En su hist\u00f3rica segunda participaci\u00f3n en unos Juegos Ol\u00edmpicos de Invierno, el mexicano Donovan Carrillo volvi\u00f3 a brillar este viernes en la final varonil del patinaje art\u00edstico de Mil\u00e1n- Cortina 2026, donde termin\u00f3 en el sitio 22 tras un total de 219.06 puntos, con lo que registr\u00f3 su mejor marca de la temporada.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"7yfUWBQRyp0\"><iframe loading=\"lazy\" title=\"Milano Cortina 2026 | Donovan Carrillo y su rutina completa en la FINAL del Patinaje Art\u00edstico \u26f8\ufe0f\u2744\ufe0f\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/7yfUWBQRyp0?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a este resultado, el atleta de 26 a\u00f1os no logr\u00f3 superar el lugar 22 que consigui\u00f3 en su primera final ol\u00edmpica, en Beijing 2022, donde obtuvo un total de 218.13 puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras su emotiva actuaci\u00f3n, la cual fue ovacionada por el p\u00fablico, el tricolor obtuvo una calificaci\u00f3n de 219.06 puntos en total, producto de la suma entre el programa corto y el libre, donde este viernes consigui\u00f3 143.50 unidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carrillo logr\u00f3 clasificar a la final luego de ubicarse en el sitio 23 en el programa corto, con 75.56 puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de participar por segunda ocasi\u00f3n en una final ol\u00edmpica, Carrillo se consolid\u00f3 como un referente del patinaje art\u00edstico, tanto en el pa\u00eds como en Latinoam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta prueba, la medalla de oro fue para el kazajo Mikhail Shaidorov (291.58), mientras los japoneses Kagiyama Yuma (280.06) y Sato Shun (274.90) se quedaron con la plata y el bronce, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estadunidense Ilia Malinin, quien luc\u00eda como favorito para coronarse en esta prueba, se qued\u00f3 fuera del podio con un total de 264.49 puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una rutina amenizada con m\u00fasica de Elvis Presley, el tapat\u00edo, ataviado con un elegante traje negro, fue el segundo competidor en salir a la pista del Milano Ice Skating Arena, donde, al ritmo de los temas My way (\u00e9ste a petici\u00f3n de su abuela materna), Trouble, Jailhouse Rock y A little less conversation, deleit\u00f3 a los presentes con su singular carisma y con ejecuciones bien logradas, las cuales incluyeron dos saltos cu\u00e1druples.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al t\u00e9rmino de su participaci\u00f3n, sorprendi\u00f3 al besar el hielo de la pista, con lo que dej\u00f3 una emotiva escena para los aficionados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs algo m\u00e1gico, esta experiencia ha sido muy especial. De inicio a fin disfrut\u00e9 mi rutina, han sido varios momentos muy especiales, como tener a mis padres por primera vez vi\u00e9ndome en unos Juegos Ol\u00edmpicos, el cari\u00f1o que recibo por parte de la audiencia. Aterrizar dos saltos cu\u00e1druples, dos triples axel en un mismo programa es hist\u00f3rico para M\u00e9xico, hay mucho aprendizaje en esta competencia y siento que sirve como un parteaguas en mi carrera deportiva porque se ve un buen resultado despu\u00e9s de dos a\u00f1os y medio entrenando en Canad\u00e1\u201d, se\u00f1al\u00f3 Carrillo en declaraciones a Claro Sports.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEspero que las condiciones con las que estoy entrenando se logren mantener por parte de las instituciones y patrocinadores que me est\u00e1n apoyando, porque creo que todav\u00eda tenemos mucho Donovan para patinaje art\u00edstico y ser\u00eda un honor, un privilegio seguir representando a mi pa\u00eds en escenarios tan importantes como este\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el tambi\u00e9n mexicano Allan Corona debut\u00f3 este viernes en Mil\u00e1n-Cortina 2026, donde, tras completar los 10 kil\u00f3metros del Cross Country, finaliz\u00f3 en el lugar 105, con un tiempo de 28 minutos y 33 segundos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su hist\u00f3rica segunda participaci\u00f3n en unos Juegos Ol\u00edmpicos de Invierno, el mexicano Donovan Carrillo volvi\u00f3 a brillar este viernes en la final varonil del patinaje art\u00edstico de Mil\u00e1n- Cortina 2026, donde termin\u00f3 en el sitio 22 tras un total de 219.06 puntos, con lo que registr\u00f3 su mejor marca de la temporada. Pese a [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":127270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-127269","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"En su hist\u00f3rica segunda participaci\u00f3n en unos Juegos Ol\u00edmpicos de Invierno, el mexicano Donovan Carrillo volvi\u00f3 a brillar este viernes en la final varonil del patinaje art\u00edstico de Mil\u00e1n- Cortina 2026, donde termin\u00f3 en el sitio 22 tras un total de 219.06 puntos, con lo que registr\u00f3 su mejor marca de la temporada. Pese a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-14T00:25:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-14T00:25:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/donvan-122402.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Jornada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Jornada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/\"},\"author\":{\"name\":\"La Jornada\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\"},\"headline\":\"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO\",\"datePublished\":\"2026-02-14T00:25:33+00:00\",\"dateModified\":\"2026-02-14T00:25:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/\"},\"wordCount\":552,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/donvan-122402.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/\",\"name\":\"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/donvan-122402.jpg\",\"datePublished\":\"2026-02-14T00:25:33+00:00\",\"dateModified\":\"2026-02-14T00:25:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/donvan-122402.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/donvan-122402.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/13\\\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\",\"name\":\"La Jornada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"caption\":\"La Jornada\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/jornada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/","og_locale":"es_MX","og_type":"article","og_title":"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO - Fuentes Fidedignas","og_description":"En su hist\u00f3rica segunda participaci\u00f3n en unos Juegos Ol\u00edmpicos de Invierno, el mexicano Donovan Carrillo volvi\u00f3 a brillar este viernes en la final varonil del patinaje art\u00edstico de Mil\u00e1n- Cortina 2026, donde termin\u00f3 en el sitio 22 tras un total de 219.06 puntos, con lo que registr\u00f3 su mejor marca de la temporada. Pese a [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-02-14T00:25:33+00:00","article_modified_time":"2026-02-14T00:25:40+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/donvan-122402.jpg","type":"image\/jpeg"}],"author":"La Jornada","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"La Jornada","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/"},"author":{"name":"La Jornada","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35"},"headline":"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO","datePublished":"2026-02-14T00:25:33+00:00","dateModified":"2026-02-14T00:25:40+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/"},"wordCount":552,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/donvan-122402.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/","name":"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/donvan-122402.jpg","datePublished":"2026-02-14T00:25:33+00:00","dateModified":"2026-02-14T00:25:40+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/donvan-122402.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/donvan-122402.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/13\/historica-participacion-de-donovan-carrillo-en-segundos-jo-invernales-termina-en-el-lugar-22-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Hist\u00f3rica participaci\u00f3n de Donovan Carrillo en segundos JO Invernales; termina en el lugar 22 | VIDEO"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35","name":"La Jornada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","caption":"La Jornada"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/jornada\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/127269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=127269"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/127269\/revisions"}],"predecessor-version":[{"id":127271,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/127269\/revisions\/127271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/127270"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=127269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=127269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=127269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}