{"id":127187,"date":"2026-02-12T20:11:45","date_gmt":"2026-02-13T03:11:45","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=127187"},"modified":"2026-02-12T20:11:45","modified_gmt":"2026-02-13T03:11:45","slug":"embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/","title":{"rendered":"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Foto: EFE <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>La representaci\u00f3n diplom\u00e1tica inform\u00f3 que ambos pa\u00edses se mantienen en contacto mientras se realizan las investigaciones para esclarecer el hecho<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Embajada de Canad\u00e1 en M\u00e9xico&nbsp;<\/strong>pidi\u00f3 a las autoridades&nbsp;justicia por la desaparici\u00f3n de&nbsp;<strong>10 mineros&nbsp;<\/strong>de una empresa de ese pa\u00eds secuestrados en&nbsp;<strong>Concordia<\/strong>, Sinaloa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de redes sociales, inform\u00f3 que ambos gobiernos se mantienen en contacto mientras se realizan las investigaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNos entristecen profundamente los sucesos en&nbsp;<strong>Sinaloa<\/strong>. Nuestro coraz\u00f3n est\u00e1 con los familiares y seres queridos de los afectados. Estamos en contacto con las autoridades mexicanas mientras contin\u00faan las labores, y esperamos que los responsables rindan cuentas ante la justicia\u201d, mencion\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/x.com\/EmbCanMexico\/status\/2022016184519184436?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E2022016184519184436%7Ctwgr%5Ebab5654fe8bd1ac8ed2453514a9ada8b69a12d0f%7Ctwcon%5Es1_c10&#038;ref_url=https%3A%2F%2Fd-3980899494591445915.ampproject.net%2F2601162341000%2Fframe.html\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa minera&nbsp;<strong>Vizsla Silver<\/strong>anunci\u00f3 este jueves que a\u00fan permanecen desaparecidos&nbsp;<strong>cinco&nbsp;<\/strong>de los 10 mineros privados de la libertad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, la compa\u00f1\u00eda canadiense subraya la incertidumbre que enfrentan las familias y se\u00f1ala que est\u00e1 colaborando con las autoridades en el marco de la investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La compa\u00f1\u00eda lamenta confirmar que cinco colegas siguen desaparecidos. Reconoce la incertidumbre y las dificultades que esto sigue generando para sus familias, sus empleados y la comunidad en general&#8221;, expresa el comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General de la Rep\u00fablica (FGR) confirm\u00f3 este lunes que identific\u00f3 a cinco de los mineros entre&nbsp;<strong>10 cuerpos&nbsp;<\/strong>hallados en una fosa clandestina en la localidad de&nbsp;<strong>El Verde<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/x.com\/AmbMacKay\/status\/2022021205579248052?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E2022021205579248052%7Ctwgr%5E5c27633f4b873722e86aa43185e4d732fca39663%7Ctwcon%5Es1_c10&#038;ref_url=https%3A%2F%2Fd-3980899494591445915.ampproject.net%2F2601162341000%2Fframe.html\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Foto: EFE La representaci\u00f3n diplom\u00e1tica inform\u00f3 que ambos pa\u00edses se mantienen en contacto mientras se realizan las investigaciones para esclarecer el hecho La&nbsp;Embajada de Canad\u00e1 en M\u00e9xico&nbsp;pidi\u00f3 a las autoridades&nbsp;justicia por la desaparici\u00f3n de&nbsp;10 mineros&nbsp;de una empresa de ese pa\u00eds secuestrados en&nbsp;Concordia, Sinaloa. A trav\u00e9s de redes sociales, inform\u00f3 que ambos gobiernos se mantienen en [&hellip;]<\/p>\n","protected":false},"author":85,"featured_media":127186,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-127187","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Foto: EFE La representaci\u00f3n diplom\u00e1tica inform\u00f3 que ambos pa\u00edses se mantienen en contacto mientras se realizan las investigaciones para esclarecer el hecho La&nbsp;Embajada de Canad\u00e1 en M\u00e9xico&nbsp;pidi\u00f3 a las autoridades&nbsp;justicia por la desaparici\u00f3n de&nbsp;10 mineros&nbsp;de una empresa de ese pa\u00eds secuestrados en&nbsp;Concordia, Sinaloa. A trav\u00e9s de redes sociales, inform\u00f3 que ambos gobiernos se mantienen en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T03:11:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/img_2561.png\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Latinus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Latinus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/\"},\"author\":{\"name\":\"Latinus\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2bf81f85e8b5d89dbb825a184aa39dde\"},\"headline\":\"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa\",\"datePublished\":\"2026-02-13T03:11:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/\"},\"wordCount\":335,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/img_2561.png\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/\",\"name\":\"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/img_2561.png\",\"datePublished\":\"2026-02-13T03:11:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/img_2561.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/img_2561.png\",\"width\":425,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/12\\\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2bf81f85e8b5d89dbb825a184aa39dde\",\"name\":\"Latinus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"caption\":\"Latinus\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/latinus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/","og_locale":"es_MX","og_type":"article","og_title":"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa - Fuentes Fidedignas","og_description":"Foto: EFE La representaci\u00f3n diplom\u00e1tica inform\u00f3 que ambos pa\u00edses se mantienen en contacto mientras se realizan las investigaciones para esclarecer el hecho La&nbsp;Embajada de Canad\u00e1 en M\u00e9xico&nbsp;pidi\u00f3 a las autoridades&nbsp;justicia por la desaparici\u00f3n de&nbsp;10 mineros&nbsp;de una empresa de ese pa\u00eds secuestrados en&nbsp;Concordia, Sinaloa. A trav\u00e9s de redes sociales, inform\u00f3 que ambos gobiernos se mantienen en [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-02-13T03:11:45+00:00","og_image":[{"width":425,"height":230,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/img_2561.png","type":"image\/png"}],"author":"Latinus","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Latinus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/"},"author":{"name":"Latinus","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2bf81f85e8b5d89dbb825a184aa39dde"},"headline":"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa","datePublished":"2026-02-13T03:11:45+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/"},"wordCount":335,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/img_2561.png","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/","name":"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/img_2561.png","datePublished":"2026-02-13T03:11:45+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/img_2561.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/img_2561.png","width":425,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/12\/embajada-de-canada-en-mexico-exige-justicia-por-mineros-desaparecidos-en-sinaloa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Embajada de Canad\u00e1 en M\u00e9xico exige justicia por mineros desaparecidos en Sinaloa"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2bf81f85e8b5d89dbb825a184aa39dde","name":"Latinus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","caption":"Latinus"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/latinus\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/127187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=127187"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/127187\/revisions"}],"predecessor-version":[{"id":127188,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/127187\/revisions\/127188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/127186"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=127187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=127187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=127187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}