{"id":126908,"date":"2026-02-09T09:33:46","date_gmt":"2026-02-09T16:33:46","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=126908"},"modified":"2026-02-09T09:34:04","modified_gmt":"2026-02-09T16:34:04","slug":"sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/","title":{"rendered":"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Durante su conferencia, la presidenta Sheinbaum se\u00f1al\u00f3 que el Instituto Nacional Electoral debe reforzar su coordinaci\u00f3n con otras autoridades, a fin de verificar los antecedentes de los candidatos.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico. Despu\u00e9s de la aprehensi\u00f3n del alcalde de Tequila, Diego Rivera, y otros colaboradores por extorsi\u00f3n y v\u00ednculos con el crimen organizado, la presidenta Claudia Sheinbaum consider\u00f3 importante reforzar los controles para la selecci\u00f3n de candidaturas que evite este tipo de v\u00ednculos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su conferencia, se\u00f1al\u00f3 que el Instituto Nacional Electoral debe reforzar su coordinaci\u00f3n con otras autoridades, a fin de verificar los antecedentes de los candidatos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro orden, Sheinbaum cuestion\u00f3 el activismo de los legisladores locales del PRI, Tania Larios y del PAN, Ra\u00fal Torres, quienes acudieron a Washington para participar en un encuentro de la extrema derecha. Asever\u00f3 que abandonar sus tareas legislativas para acudir a este tipo de reuniones de organismos, que son extremadamente conservadores, con todas las implicaciones de clasismo y racismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante su conferencia, la presidenta Sheinbaum se\u00f1al\u00f3 que el Instituto Nacional Electoral debe reforzar su coordinaci\u00f3n con otras autoridades, a fin de verificar los antecedentes de los candidatos. M\u00e9xico. Despu\u00e9s de la aprehensi\u00f3n del alcalde de Tequila, Diego Rivera, y otros colaboradores por extorsi\u00f3n y v\u00ednculos con el crimen organizado, la presidenta Claudia Sheinbaum consider\u00f3 [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":89423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-126908","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Durante su conferencia, la presidenta Sheinbaum se\u00f1al\u00f3 que el Instituto Nacional Electoral debe reforzar su coordinaci\u00f3n con otras autoridades, a fin de verificar los antecedentes de los candidatos. M\u00e9xico. Despu\u00e9s de la aprehensi\u00f3n del alcalde de Tequila, Diego Rivera, y otros colaboradores por extorsi\u00f3n y v\u00ednculos con el crimen organizado, la presidenta Claudia Sheinbaum consider\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-09T16:33:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T16:34:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/sesion-ine-23ago24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Jornada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Jornada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/\"},\"author\":{\"name\":\"La Jornada\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\"},\"headline\":\"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila\",\"datePublished\":\"2026-02-09T16:33:46+00:00\",\"dateModified\":\"2026-02-09T16:34:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/\"},\"wordCount\":181,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/sesion-ine-23ago24.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/\",\"name\":\"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/sesion-ine-23ago24.jpg\",\"datePublished\":\"2026-02-09T16:33:46+00:00\",\"dateModified\":\"2026-02-09T16:34:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/sesion-ine-23ago24.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/sesion-ine-23ago24.jpg\",\"width\":650,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/09\\\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\",\"name\":\"La Jornada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"caption\":\"La Jornada\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/jornada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/","og_locale":"es_MX","og_type":"article","og_title":"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila - Fuentes Fidedignas","og_description":"Durante su conferencia, la presidenta Sheinbaum se\u00f1al\u00f3 que el Instituto Nacional Electoral debe reforzar su coordinaci\u00f3n con otras autoridades, a fin de verificar los antecedentes de los candidatos. M\u00e9xico. Despu\u00e9s de la aprehensi\u00f3n del alcalde de Tequila, Diego Rivera, y otros colaboradores por extorsi\u00f3n y v\u00ednculos con el crimen organizado, la presidenta Claudia Sheinbaum consider\u00f3 [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-02-09T16:33:46+00:00","article_modified_time":"2026-02-09T16:34:04+00:00","og_image":[{"width":650,"height":433,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/sesion-ine-23ago24.jpg","type":"image\/jpeg"}],"author":"La Jornada","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"La Jornada","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/"},"author":{"name":"La Jornada","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35"},"headline":"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila","datePublished":"2026-02-09T16:33:46+00:00","dateModified":"2026-02-09T16:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/"},"wordCount":181,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/sesion-ine-23ago24.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/","name":"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/sesion-ine-23ago24.jpg","datePublished":"2026-02-09T16:33:46+00:00","dateModified":"2026-02-09T16:34:04+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/sesion-ine-23ago24.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/sesion-ine-23ago24.jpg","width":650,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/09\/sheinbaum-urge-al-ine-endurecer-filtros-a-candidatos-tras-captura-del-alcalde-de-tequila\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Sheinbaum urge al INE endurecer filtros a candidatos tras captura del alcalde de Tequila"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35","name":"La Jornada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","caption":"La Jornada"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/jornada\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=126908"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126908\/revisions"}],"predecessor-version":[{"id":126909,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126908\/revisions\/126909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/89423"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=126908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=126908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=126908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}