{"id":126790,"date":"2026-02-06T09:18:10","date_gmt":"2026-02-06T16:18:10","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=126790"},"modified":"2026-02-06T09:18:20","modified_gmt":"2026-02-06T16:18:20","slug":"sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/","title":{"rendered":"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional"},"content":{"rendered":"\n<p><strong><em>La Presidenta se\u00f1al\u00f3 que ahora el General Cort\u00e9s asumir\u00e1 el cargo de oficial mayor en la Secretar\u00eda de la Defensa Nacional.<\/em><\/strong><\/p>\n\n\n\n<p>En La Ma\u00f1anera del Pueblo de este 6 de febrero, la presidenta Claudia Sheinbaum anunci\u00f3 cambios relevantes en la estructura de seguridad nacional.<\/p>\n\n\n\n<p>En la conferencia matutina fue presentado el General Guillermo Brise\u00f1o Lobera\u00a0designado como nuevo comandante de la Guardia Nacional.<\/p>\n\n\n\n<p>Durante el anuncio, Sheinbaum destac\u00f3 que el relevo busca fortalecer la estrategia de seguridad y garantizar continuidad en las labores de la corporaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Asimismo, inform\u00f3 que el General Hern\u00e1n Cort\u00e9s Hern\u00e1ndez asumir\u00e1 el cargo de oficial mayor de la Secretar\u00eda de la Defensa Nacional (Sedena), posici\u00f3n clave en la administraci\u00f3n de recursos y operaciones de la dependencia.<\/p>\n\n\n\n<p>Con estos nombramientos, el gobierno federal refuerza la coordinaci\u00f3n entre la Guardia Nacional y la Sedena, instituciones que sirven a la seguridad p\u00fablica del pa\u00eds.<\/p>\n\n\n\n<p><strong>\u00bfQui\u00e9n es Guillermo Brise\u00f1o Lobera?\u00a0<\/strong><\/p>\n\n\n\n<p>El General Guillermo Brise\u00f1o Lobera cuenta con una amplia y reconocida trayectoria dentro de las Fuerzas Armadas, iniciada en 1981 con su ingreso al Heroico Colegio Militar.&nbsp;<\/p>\n\n\n\n<p>A lo largo de m\u00e1s de cuatro d\u00e9cadas de servicio ha ocupado cargos de alta responsabilidad, entre los que sobresale la Comandancia de la Tercera Regi\u00f3n Militar, con jurisdicci\u00f3n en los estados de Sinaloa y Durango, donde encabez\u00f3 operaciones estrat\u00e9gicas en materia de seguridad.<\/p>\n\n\n\n<p>Brise\u00f1o Lobera asume la Comandancia de la Guardia Nacional en relevo del General de Divisi\u00f3n Hern\u00e1n Cort\u00e9s Hern\u00e1ndez, quien se desempe\u00f1\u00f3 como titular de esta instituci\u00f3n de seguridad p\u00fablica desde el 1 de octubre de 2024.<\/p>\n\n\n\n<p><strong>Toma de protesta<\/strong><br>El lunes 2 de febrero, por instrucci\u00f3n de la presidenta de la Rep\u00fablica, Claudia Sheinbaum, el secretario de la Defensa Nacional, General Ricardo Trevilla Trejo, tom\u00f3 protesta al General de Divisi\u00f3n de Guardia Nacional de Estado Mayor, Guillermo Brise\u00f1o Lobera, como nuevo comandante de la Guardia Nacional.<\/p>\n\n\n\n<p>La ceremonia protocolaria se realiz\u00f3 en la Plaza de la Lealtad, dentro de las instalaciones de la Secretar\u00eda de la Defensa Nacional, donde el General Brise\u00f1o Lobera asumi\u00f3 formalmente el cargo y rindi\u00f3 la protesta de bandera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidenta se\u00f1al\u00f3 que ahora el General Cort\u00e9s asumir\u00e1 el cargo de oficial mayor en la Secretar\u00eda de la Defensa Nacional. En La Ma\u00f1anera del Pueblo de este 6 de febrero, la presidenta Claudia Sheinbaum anunci\u00f3 cambios relevantes en la estructura de seguridad nacional. En la conferencia matutina fue presentado el General Guillermo Brise\u00f1o Lobera\u00a0designado [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":126791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-126790","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La Presidenta se\u00f1al\u00f3 que ahora el General Cort\u00e9s asumir\u00e1 el cargo de oficial mayor en la Secretar\u00eda de la Defensa Nacional. En La Ma\u00f1anera del Pueblo de este 6 de febrero, la presidenta Claudia Sheinbaum anunci\u00f3 cambios relevantes en la estructura de seguridad nacional. En la conferencia matutina fue presentado el General Guillermo Brise\u00f1o Lobera\u00a0designado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T16:18:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T16:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/General-Guillermo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milenio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milenio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/\"},\"author\":{\"name\":\"Milenio\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/47ec0135738f4b0c7495f06a77a2c976\"},\"headline\":\"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional\",\"datePublished\":\"2026-02-06T16:18:10+00:00\",\"dateModified\":\"2026-02-06T16:18:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/\"},\"wordCount\":390,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/General-Guillermo.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/\",\"name\":\"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/General-Guillermo.jpg\",\"datePublished\":\"2026-02-06T16:18:10+00:00\",\"dateModified\":\"2026-02-06T16:18:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/General-Guillermo.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/General-Guillermo.jpg\",\"width\":500,\"height\":335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/47ec0135738f4b0c7495f06a77a2c976\",\"name\":\"Milenio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"caption\":\"Milenio\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/milenio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/","og_locale":"es_MX","og_type":"article","og_title":"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional - Fuentes Fidedignas","og_description":"La Presidenta se\u00f1al\u00f3 que ahora el General Cort\u00e9s asumir\u00e1 el cargo de oficial mayor en la Secretar\u00eda de la Defensa Nacional. En La Ma\u00f1anera del Pueblo de este 6 de febrero, la presidenta Claudia Sheinbaum anunci\u00f3 cambios relevantes en la estructura de seguridad nacional. En la conferencia matutina fue presentado el General Guillermo Brise\u00f1o Lobera\u00a0designado [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-02-06T16:18:10+00:00","article_modified_time":"2026-02-06T16:18:20+00:00","og_image":[{"width":500,"height":335,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/General-Guillermo.jpg","type":"image\/jpeg"}],"author":"Milenio","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Milenio","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/"},"author":{"name":"Milenio","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/47ec0135738f4b0c7495f06a77a2c976"},"headline":"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional","datePublished":"2026-02-06T16:18:10+00:00","dateModified":"2026-02-06T16:18:20+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/"},"wordCount":390,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/General-Guillermo.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/","name":"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/General-Guillermo.jpg","datePublished":"2026-02-06T16:18:10+00:00","dateModified":"2026-02-06T16:18:20+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/General-Guillermo.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/General-Guillermo.jpg","width":500,"height":335},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/sheinbaum-presenta-a-guillermo-briseno-como-nuevo-comandante-de-la-guardia-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Sheinbaum presenta a Guillermo Brise\u00f1o como nuevo comandante de la Guardia Nacional"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/47ec0135738f4b0c7495f06a77a2c976","name":"Milenio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","caption":"Milenio"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/milenio\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=126790"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126790\/revisions"}],"predecessor-version":[{"id":126792,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126790\/revisions\/126792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/126791"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=126790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=126790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=126790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}