{"id":126736,"date":"2026-02-06T01:10:00","date_gmt":"2026-02-06T08:10:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=126736"},"modified":"2026-02-05T13:13:22","modified_gmt":"2026-02-05T20:13:22","slug":"ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/","title":{"rendered":"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT"},"content":{"rendered":"\n<p><strong><em>El togado de la SCJN se\u00f1ala que, aunque la norma vigente en Sinaloa protege a grupos vulnerables, es confusa.<\/em><\/strong><\/p>\n\n\n\n<p>Un ministro de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) plantear\u00e1 invalidar la reforma que entr\u00f3 en vigor en Sinaloa y castiga con uno a tres a\u00f1os de prisi\u00f3n a quienes en redes sociales difunden discursos de odio contra la comunidad LGBT.<\/p>\n\n\n\n<p>El togado reconoci\u00f3 la intenci\u00f3n del congreso local por proteger a los grupos vulnerables, pero enfatiz\u00f3 que la norma vigente desde hace casi dos a\u00f1os es confusa.<\/p>\n\n\n\n<p>El asunto ser\u00e1 debatido el martes 3 de febrero, cuando Ar\u00edstides Guerrero Garc\u00eda, ministro instructor, presente un proyecto en el que propone declarar fundados los alegatos de la Presidencia de la Rep\u00fablica, la cual promovi\u00f3 una acci\u00f3n de inconstitucionalidad en la que impugn\u00f3 la fracci\u00f3n I, del art\u00edculo 189, del C\u00f3digo Penal de la citada entidad.<\/p>\n\n\n\n<p><strong>Discursos de odio, sin consecuencias legales en redes<\/strong><br>En sus argumentos, el legislativo local se\u00f1al\u00f3 que el discurso de odio en M\u00e9xico ha aumentado dr\u00e1sticamente contra la comunidad LGBT, particularmente en redes sociales, donde personas provocan, incitan y difunden expresiones discriminatorias con impunidad.<\/p>\n\n\n\n<p>Asimismo, indic\u00f3 que el problema es que estas conductas (provocar, incitar, apoyar o difundir acciones o expresiones verbales y\/o escritas que denoten la dignidad de las personas basadas en odio) no est\u00e1n adecuadamente tipificadas ni sancionadas.<\/p>\n\n\n\n<p>Lo anterior permite que los discursos discriminatorios se multipliquen sin consecuencias legales, generando un clima de hostilidad que puede propiciar actos violentos contra grupos vulnerables.<\/p>\n\n\n\n<p>Por esta raz\u00f3n, impuls\u00f3 la reforma, estableciendo que se impondr\u00e1n de uno a tres a\u00f1os de prisi\u00f3n y multa de 50 a 200 d\u00edas, a quien incite y apoye a difundir acciones o expresiones verbales o escritas de cualquier tipo basadas en odio, violencia o discriminaci\u00f3n contra cualquier persona o grupos de personas.<\/p>\n\n\n\n<p><strong>Persisten problemas sist\u00e9micos de violencia, discriminaci\u00f3n y exclusi\u00f3n<\/strong><br>Guerrero Garc\u00eda reconoci\u00f3 que personas lesbianas, gay, bisexuales, trans e intersexuales han estado hist\u00f3ricamente sometidas a discriminaci\u00f3n por su orientaci\u00f3n sexual, identidad y expresi\u00f3n de g\u00e9nero, y diversidad corporal.<\/p>\n\n\n\n<p>Puntualiz\u00f3 que la Comisi\u00f3n Interamericana de Derechos Humanos, a trav\u00e9s de su Relator\u00eda especializada, ha alertado que las personas LGBT contin\u00faan siendo sujetas a discriminaci\u00f3n, violencia, persecuci\u00f3n y otros abusos que vulneran sus derechos.<\/p>\n\n\n\n<p>Adem\u00e1s, los problemas sist\u00e9micos que enfrentan en la regi\u00f3n incluyen la criminalizaci\u00f3n, los altos \u00edndices de violencia e impunidad, la discriminaci\u00f3n en el acceso a servicios de salud, justicia y educaci\u00f3n, las barreras para la inserci\u00f3n laboral y la participaci\u00f3n pol\u00edtica, as\u00ed como la exclusi\u00f3n.<\/p>\n\n\n\n<p>\u201c\u2026 esta SCJN reconoce plenamente el contexto de discriminaci\u00f3n estructural, violencia sistem\u00e1tica y exclusi\u00f3n social que hist\u00f3ricamente han enfrentado las personas LGBT, particularmente las personas trans y de g\u00e9nero diverso, tanto en el \u00e1mbito internacional como en el nacional\u201d.<\/p>\n\n\n\n<p>Sin embargo, dijo el togado, el reconocimiento de estas obligaciones estatales y la legitimidad de los fines que persigue la norma impugnada no eximen al Alto Tribunal de verificar que las reformas emitidas por los \u00f3rganos legislativos se ajusten a los par\u00e1metros establecidos en la Constituci\u00f3n federal y en los tratados internacionales de derechos humanos.<\/p>\n\n\n\n<p>\u201cEn conclusi\u00f3n, los tres verbos rectores que configuran las modalidades de conducta de la fracci\u00f3n I del multicitado numeral \u2014\u2018provoque\u2019, \u2018incite\u2019 y \u2018apoye a difundir\u2019\u2014 adolecen de imprecisi\u00f3n excesiva que vulnera el principio de taxatividad.\u00a0<\/p>\n\n\n\n<p>\u201cSi bien cada uno presenta particularidades (los diferentes significados de \u2018provocar\u2019, la falta de criterios delimitadores de \u2018incitar\u2019, y la amplitud ilimitada de \u2018apoyar a difundir\u2019), todos comparten un problema estructural com\u00fan: admiten un espectro de significados tan amplio que impiden al ciudadano conocer qu\u00e9 conductas est\u00e1n prohibidas, y los dem\u00e1s elementos del tipo no compensan, sino que replican esta indeterminaci\u00f3n\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>De aprobarse el proyecto, la sentencia tendr\u00e1 efectos retroactivos por tratarse de materia penal, es decir, se tendr\u00e1n que echar abajo condenas impuestas por este delito\u00a0a partir del 20 de agosto de 2024, fecha en que entr\u00f3 en vigor la norma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El togado de la SCJN se\u00f1ala que, aunque la norma vigente en Sinaloa protege a grupos vulnerables, es confusa. Un ministro de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) plantear\u00e1 invalidar la reforma que entr\u00f3 en vigor en Sinaloa y castiga con uno a tres a\u00f1os de prisi\u00f3n a quienes en redes sociales [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":80759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":{"0":"post-126736","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-amor-es-amor","8":"category-semanales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El togado de la SCJN se\u00f1ala que, aunque la norma vigente en Sinaloa protege a grupos vulnerables, es confusa. Un ministro de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) plantear\u00e1 invalidar la reforma que entr\u00f3 en vigor en Sinaloa y castiga con uno a tres a\u00f1os de prisi\u00f3n a quienes en redes sociales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T08:10:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milenio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milenio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/\"},\"author\":{\"name\":\"Milenio\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/47ec0135738f4b0c7495f06a77a2c976\"},\"headline\":\"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT\",\"datePublished\":\"2026-02-06T08:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/\"},\"wordCount\":722,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/\",\"name\":\"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"datePublished\":\"2026-02-06T08:10:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/06\\\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/47ec0135738f4b0c7495f06a77a2c976\",\"name\":\"Milenio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g\",\"caption\":\"Milenio\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/milenio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/","og_locale":"es_MX","og_type":"article","og_title":"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT - Fuentes Fidedignas","og_description":"El togado de la SCJN se\u00f1ala que, aunque la norma vigente en Sinaloa protege a grupos vulnerables, es confusa. Un ministro de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) plantear\u00e1 invalidar la reforma que entr\u00f3 en vigor en Sinaloa y castiga con uno a tres a\u00f1os de prisi\u00f3n a quienes en redes sociales [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-02-06T08:10:00+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","type":"image\/jpeg"}],"author":"Milenio","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Milenio","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/"},"author":{"name":"Milenio","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/47ec0135738f4b0c7495f06a77a2c976"},"headline":"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT","datePublished":"2026-02-06T08:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/"},"wordCount":722,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/","name":"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","datePublished":"2026-02-06T08:10:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/06\/ministro-propone-invalidar-reforma-sobre-discursos-de-odio-en-redes-contra-comunidad-lgbt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Ministro propone invalidar reforma sobre discursos de odio en redes contra comunidad LGBT"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/47ec0135738f4b0c7495f06a77a2c976","name":"Milenio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/acabf7b54753e51c2c76457954577c236b3b764789b19879565769739d1e4a75?s=96&d=mm&r=g","caption":"Milenio"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/milenio\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=126736"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126736\/revisions"}],"predecessor-version":[{"id":126737,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126736\/revisions\/126737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/80759"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=126736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=126736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=126736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}