{"id":126520,"date":"2026-02-03T06:59:05","date_gmt":"2026-02-03T13:59:05","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=126520"},"modified":"2026-02-03T07:01:18","modified_gmt":"2026-02-03T14:01:18","slug":"diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/","title":{"rendered":"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>En el atentado, Montoya sufri\u00f3 heridas importantes que requirieron atenci\u00f3n especializada, incluyendo cirug\u00eda reconstructiva, aunque su estado se mantuvo estable en todo momento bajo cuidados m\u00e9dicos.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada local, Elizabeth Rafaela Montoya Ojeda, integrante de Movimiento Ciudadano, ha recibido el alta m\u00e9dica tras su hospitalizaci\u00f3n derivada del atentado armado en el que result\u00f3 lesionada, informaron autoridades de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ataque ocurri\u00f3 el 28 de enero de 2026 en el centro de Culiac\u00e1n, Sinaloa, cuando Montoya y el diputado, Sergio Torres F\u00e9lix, eran atacados a balazos mientras circulaban por la avenida Paseo Ni\u00f1os H\u00e9roes, tras salir del Congreso del estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos fueron heridos durante la agresi\u00f3n por un grupo armado, en un hecho que activ\u00f3 un amplio despliegue de seguridad en la capital sinaloense. Montoya recibi\u00f3 atenci\u00f3n m\u00e9dica inmediata y, aunque inicialmente no se hab\u00eda definido una fecha de alta hospitalaria por la gravedad de sus lesiones, los m\u00e9dicos determinaron que pod\u00eda continuar su recuperaci\u00f3n fuera del hospital tras la evoluci\u00f3n favorable de su estado de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el atentado, Montoya sufri\u00f3 heridas importantes que requirieron atenci\u00f3n especializada, incluyendo cirug\u00eda reconstructiva, aunque su estado se mantuvo estable en todo momento bajo cuidados m\u00e9dicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el diputado, Sergio Torres F\u00e9lix, contin\u00faa en estado cr\u00edtico y bajo observaci\u00f3n en terapia intensiva, con mejor\u00edas leves pero significativas, de acuerdo con el \u00faltimo reporte de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho ha sido considerado un episodio m\u00e1s de la violencia pol\u00edtica y criminal que se vive en la entidad, y las autoridades federales y estatales mantienen avances en las investigaciones para identificar y detener a los responsables del ataque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella se encontraba en la cl\u00ednica Cemsi. Seg\u00fan la informaci\u00f3n que se dio durante la semana, la diputada del MC perdi\u00f3 un ojo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el atentado, Montoya sufri\u00f3 heridas importantes que requirieron atenci\u00f3n especializada, incluyendo cirug\u00eda reconstructiva, aunque su estado se mantuvo estable en todo momento bajo cuidados m\u00e9dicos. La diputada local, Elizabeth Rafaela Montoya Ojeda, integrante de Movimiento Ciudadano, ha recibido el alta m\u00e9dica tras su hospitalizaci\u00f3n derivada del atentado armado en el que result\u00f3 lesionada, informaron [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":126521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[38],"tags":[],"class_list":["post-126520","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-locales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"En el atentado, Montoya sufri\u00f3 heridas importantes que requirieron atenci\u00f3n especializada, incluyendo cirug\u00eda reconstructiva, aunque su estado se mantuvo estable en todo momento bajo cuidados m\u00e9dicos. La diputada local, Elizabeth Rafaela Montoya Ojeda, integrante de Movimiento Ciudadano, ha recibido el alta m\u00e9dica tras su hospitalizaci\u00f3n derivada del atentado armado en el que result\u00f3 lesionada, informaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T13:59:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T14:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/Elizabeth-Montoya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"316\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Jornada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Jornada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/\"},\"author\":{\"name\":\"La Jornada\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\"},\"headline\":\"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n\",\"datePublished\":\"2026-02-03T13:59:05+00:00\",\"dateModified\":\"2026-02-03T14:01:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Elizabeth-Montoya.jpg\",\"articleSection\":[\"NOTICIAS LOCALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/\",\"name\":\"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Elizabeth-Montoya.jpg\",\"datePublished\":\"2026-02-03T13:59:05+00:00\",\"dateModified\":\"2026-02-03T14:01:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Elizabeth-Montoya.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Elizabeth-Montoya.jpg\",\"width\":500,\"height\":316},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/02\\\/03\\\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\",\"name\":\"La Jornada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"caption\":\"La Jornada\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/jornada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/","og_locale":"es_MX","og_type":"article","og_title":"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n - Fuentes Fidedignas","og_description":"En el atentado, Montoya sufri\u00f3 heridas importantes que requirieron atenci\u00f3n especializada, incluyendo cirug\u00eda reconstructiva, aunque su estado se mantuvo estable en todo momento bajo cuidados m\u00e9dicos. La diputada local, Elizabeth Rafaela Montoya Ojeda, integrante de Movimiento Ciudadano, ha recibido el alta m\u00e9dica tras su hospitalizaci\u00f3n derivada del atentado armado en el que result\u00f3 lesionada, informaron [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-02-03T13:59:05+00:00","article_modified_time":"2026-02-03T14:01:18+00:00","og_image":[{"width":500,"height":316,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/Elizabeth-Montoya.jpg","type":"image\/jpeg"}],"author":"La Jornada","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"La Jornada","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/"},"author":{"name":"La Jornada","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35"},"headline":"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n","datePublished":"2026-02-03T13:59:05+00:00","dateModified":"2026-02-03T14:01:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/Elizabeth-Montoya.jpg","articleSection":["NOTICIAS LOCALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/","name":"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/Elizabeth-Montoya.jpg","datePublished":"2026-02-03T13:59:05+00:00","dateModified":"2026-02-03T14:01:18+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/Elizabeth-Montoya.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/02\/Elizabeth-Montoya.jpg","width":500,"height":316},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/02\/03\/diputada-de-mc-elizabeth-montoya-recibe-alta-medica-tras-ataque-en-culiacan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Diputada de MC, Elizabeth Montoya recibe alta m\u00e9dica tras ataque en Culiac\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35","name":"La Jornada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","caption":"La Jornada"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/jornada\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=126520"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126520\/revisions"}],"predecessor-version":[{"id":126523,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/126520\/revisions\/126523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/126521"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=126520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=126520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=126520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}