{"id":123835,"date":"2025-12-15T20:47:06","date_gmt":"2025-12-16T03:47:06","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=123835"},"modified":"2025-12-15T20:47:06","modified_gmt":"2025-12-16T03:47:06","slug":"mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/","title":{"rendered":"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>A trav\u00e9s de un comunicado de prensa difundido por el m\u00e1ximo organismo rector del b\u00e9isbol del Caribe, se dio a conocer que tres pa\u00edses han indicado que las condiciones no est\u00e1n dadas para celebrar la Serie del Caribe 2026 en Venezuela.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Confederaci\u00f3n de B\u00e9isbol Profesional del Caribe (CBPC) anunci\u00f3 que la Liga ARCO Mexicana del Pac\u00edfico, la Liga de B\u00e9isbol Profesional Roberto Clemente (LBPRC) de Puerto Rico y la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana (LIDOM) han declinado participar en la Serie del Caribe 2026, programada para celebrarse en Venezuela entre el 1 y el 7 de febrero de ese a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante un comunicado de prensa hecho p\u00fablico la noche de este lunes 15 de diciembre, la<strong>CBPC&nbsp;<\/strong>inform\u00f3 que las tres ligas coincidieron en se\u00f1alar que no existen las condiciones necesarias para que el evento se lleve a cabo en territorio venezolano, tomando en cuenta la situaci\u00f3n pol\u00edtica y militar que atraviesa el pa\u00eds, en el marco del conflicto con los Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>La Confederaci\u00f3n de B\u00e9isbol Profesional del Caribe (CBPC) informa que, en el marco de una Asamblea General Extraordinaria, las ligas miembros de Puerto Rico, Rep\u00fablica Dominicana y M\u00e9xico comunicaron formalmente que, debido a situaciones externas ajenas a su control, no se encuentran en capacidad de asistir a la Serie del Caribe 2026, programada del 1 al 7 de febrero en Venezuela<\/em>\u201d, se\u00f1ala&nbsp;el comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>La CBPC deja constancia de que dicha comunicaci\u00f3n fue recibida en un marco de respeto institucional y conforme a los procedimientos internos de la Confederaci\u00f3n. Asimismo, reconoce la posici\u00f3n de la Liga Venezolana de B\u00e9isbol Profesional (LVBP), que ha reiterado contar con las condiciones organizativas necesarias para la realizaci\u00f3n del evento. La Confederaci\u00f3n, junto a sus ligas miembro, reconoce y valora el trabajo desarrollado por la LVBP y su Comit\u00e9 Organizador, as\u00ed como los esfuerzos realizados en la planificaci\u00f3n de la Serie del Caribe 2026<\/em>\u201d, agrega el texto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La<strong>&nbsp;Confederaci\u00f3n<\/strong>&nbsp;indic\u00f3 que continuar\u00e1 dando seguimiento a la situaci\u00f3n y evaluando distintas alternativas, con el objetivo de anunciar oportunamente la decisi\u00f3n que se tomar\u00e1 respecto al torneo de 2026. Con la declinaci\u00f3n de tres de sus ligas miembros, el evento quedar\u00eda, por el momento, \u00fanicamente con&nbsp;<strong>Venezuela&nbsp;<\/strong>como pa\u00eds sede, junto a los invitados<strong>&nbsp;Colombia<\/strong>,&nbsp;<strong>Cuba<\/strong>,&nbsp;<strong>Panam\u00e1&nbsp;<\/strong>y el equipo<strong>&nbsp;Japan Breeze<\/strong>, de&nbsp;<strong>Jap\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En caso de que el evento finalmente no se celebre en&nbsp;<strong>Venezuela<\/strong>, podr\u00eda contemplarse una sede alternativa en alguno de los pa\u00edses invitados, tal como ocurri\u00f3 en 2019, cuando debido a la situaci\u00f3n pol\u00edtica venezolana, el torneo termin\u00f3 disput\u00e1ndose en&nbsp;<strong>Panam\u00e1<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de un comunicado de prensa difundido por el m\u00e1ximo organismo rector del b\u00e9isbol del Caribe, se dio a conocer que tres pa\u00edses han indicado que las condiciones no est\u00e1n dadas para celebrar la Serie del Caribe 2026 en Venezuela. La Confederaci\u00f3n de B\u00e9isbol Profesional del Caribe (CBPC) anunci\u00f3 que la Liga ARCO Mexicana [&hellip;]<\/p>\n","protected":false},"author":56,"featured_media":123834,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-123835","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"A trav\u00e9s de un comunicado de prensa difundido por el m\u00e1ximo organismo rector del b\u00e9isbol del Caribe, se dio a conocer que tres pa\u00edses han indicado que las condiciones no est\u00e1n dadas para celebrar la Serie del Caribe 2026 en Venezuela. La Confederaci\u00f3n de B\u00e9isbol Profesional del Caribe (CBPC) anunci\u00f3 que la Liga ARCO Mexicana [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-16T03:47:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/12\/img_8423.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ESPN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ESPN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/\"},\"author\":{\"name\":\"ESPN\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/7fe026938fb0ad9958949de167b7588c\"},\"headline\":\"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela\",\"datePublished\":\"2025-12-16T03:47:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/img_8423.jpg\",\"articleSection\":[\"NOTA PRINCIPAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/\",\"name\":\"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/img_8423.jpg\",\"datePublished\":\"2025-12-16T03:47:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/img_8423.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/img_8423.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/12\\\/15\\\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/7fe026938fb0ad9958949de167b7588c\",\"name\":\"ESPN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a7c694b6f48b567dbf58684dc87e55e259e8332b6c80c05cc5bd7273ec1e7ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a7c694b6f48b567dbf58684dc87e55e259e8332b6c80c05cc5bd7273ec1e7ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a7c694b6f48b567dbf58684dc87e55e259e8332b6c80c05cc5bd7273ec1e7ea?s=96&d=mm&r=g\",\"caption\":\"ESPN\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/espn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/","og_locale":"es_MX","og_type":"article","og_title":"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela - Fuentes Fidedignas","og_description":"A trav\u00e9s de un comunicado de prensa difundido por el m\u00e1ximo organismo rector del b\u00e9isbol del Caribe, se dio a conocer que tres pa\u00edses han indicado que las condiciones no est\u00e1n dadas para celebrar la Serie del Caribe 2026 en Venezuela. La Confederaci\u00f3n de B\u00e9isbol Profesional del Caribe (CBPC) anunci\u00f3 que la Liga ARCO Mexicana [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2025-12-16T03:47:06+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/12\/img_8423.jpg","type":"image\/jpeg"}],"author":"ESPN","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"ESPN","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/"},"author":{"name":"ESPN","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/7fe026938fb0ad9958949de167b7588c"},"headline":"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela","datePublished":"2025-12-16T03:47:06+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/"},"wordCount":482,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/12\/img_8423.jpg","articleSection":["NOTA PRINCIPAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/","name":"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/12\/img_8423.jpg","datePublished":"2025-12-16T03:47:06+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/12\/img_8423.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/12\/img_8423.jpg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/12\/15\/mexico-puerto-rico-y-dominicana-renuncian-a-la-serie-del-caribe-2026-en-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico, Puerto Rico y Dominicana renuncian a la Serie del Caribe 2026 en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/7fe026938fb0ad9958949de167b7588c","name":"ESPN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1a7c694b6f48b567dbf58684dc87e55e259e8332b6c80c05cc5bd7273ec1e7ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1a7c694b6f48b567dbf58684dc87e55e259e8332b6c80c05cc5bd7273ec1e7ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a7c694b6f48b567dbf58684dc87e55e259e8332b6c80c05cc5bd7273ec1e7ea?s=96&d=mm&r=g","caption":"ESPN"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/espn\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/123835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=123835"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/123835\/revisions"}],"predecessor-version":[{"id":123836,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/123835\/revisions\/123836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/123834"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=123835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=123835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=123835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}