{"id":1222,"date":"2021-05-06T08:31:34","date_gmt":"2021-05-06T15:31:34","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=1222"},"modified":"2021-05-06T08:31:36","modified_gmt":"2021-05-06T15:31:36","slug":"amlo-dice-que-ine-fue-creado-para-impedir-la-democracia","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/","title":{"rendered":"AMLO dice que INE fue creado para impedir la democracia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>L\u00f3pez Obrador pidi\u00f3 que se denuncien la entrega de despensas, dinero o amenazas que se hagan para obtener el voto a favor de un candidato.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador critic\u00f3 al Instituto Nacional Electoral (INE), dijo que el organismo no investiga la supuesta compra de votos por parte del candidato del PRI para el gobierno de Nuevo Le\u00f3n, Adri\u00e1n de la Garza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa paradoja es que el INE en lugar de garantizar la democracia, ha sido creado y funciona para impedir la democracia. Eso es lo que estamos viendo, porque esto (la supuesta compra de votos) no lo ve el INE. Se hacen de la vista gorda\u201d, dijo el mandatario durante su conferencia de prensa matutina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante las cr\u00edticas de que viola la veda electoral al referirse a las elecciones, L\u00f3pez Obrador respondi\u00f3 que todos los mexicanos tienen la obligaci\u00f3n de hacer realidad la democracia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfC\u00f3mo creen que me voy a quedar callado? si esto es lo que m\u00e1s ha da\u00f1ado y ha impedido que en M\u00e9xico haya una aut\u00e9ntica democracia. \u00bfC\u00f3mo me voy a quedar callado ante la compra del voto? Sea del partido que sea, si hay acciones fraudulentas, se tienen que denunciar. Si no para qu\u00e9 se reform\u00f3 la Constituci\u00f3n con el prop\u00f3sito de que el fraude electoral sea considerado delito grave\u201d, fustig\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario pidi\u00f3 que se denuncien la entrega de despensas, de dinero o las amenazas que se hagan para obtener el voto a favor de un candidato, pues dijo que no se debe pensar que los \u00f3rganos electorales, como el INE, van a garantizar la democracia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay que denunciar entrega de despensas, de dinero, las amenazas. Todos tenemos que ayudar. Estas tienen que ser las elecciones m\u00e1s limpias, libres en la historia de M\u00e9xico. No pensar que la democracia la va a garantizar el INE el TRIFE, pues han sido los m\u00e1s tenaces violadores de la ley y los m\u00e1s opositores a la democracia\u201d, se\u00f1al\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00f3pez Obrador pidi\u00f3 que se denuncien la entrega de despensas, dinero o amenazas que se hagan para obtener el voto a favor de un candidato. Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador critic\u00f3 al Instituto Nacional Electoral (INE), dijo que el organismo no investiga la supuesta compra de votos por parte del candidato [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[247,297,276,264,263],"class_list":["post-1222","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales","tag-amlo","tag-andres-manuel-lopez-obrador","tag-elecciones-2021","tag-ine","tag-instituto-nacional-electoral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMLO dice que INE fue creado para impedir la democracia - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMLO dice que INE fue creado para impedir la democracia - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"L\u00f3pez Obrador pidi\u00f3 que se denuncien la entrega de despensas, dinero o amenazas que se hagan para obtener el voto a favor de un candidato. Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador critic\u00f3 al Instituto Nacional Electoral (INE), dijo que el organismo no investiga la supuesta compra de votos por parte del candidato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-06T15:31:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-06T15:31:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/amlo-abr-29-640x360-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Forbes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Forbes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/\"},\"author\":{\"name\":\"Forbes\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/5623d53fe2e579d825b1679734abcc44\"},\"headline\":\"AMLO dice que INE fue creado para impedir la democracia\",\"datePublished\":\"2021-05-06T15:31:34+00:00\",\"dateModified\":\"2021-05-06T15:31:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/\"},\"wordCount\":359,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/amlo-abr-29-640x360-1.jpg\",\"keywords\":[\"AMLO\",\"Andr\u00e9s Manuel L\u00f3pez Obrador\",\"Elecciones 2021\",\"INE\",\"Instituto Nacional Electoral\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/\",\"name\":\"AMLO dice que INE fue creado para impedir la democracia - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/amlo-abr-29-640x360-1.jpg\",\"datePublished\":\"2021-05-06T15:31:34+00:00\",\"dateModified\":\"2021-05-06T15:31:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/amlo-abr-29-640x360-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/amlo-abr-29-640x360-1.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/06\\\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMLO dice que INE fue creado para impedir la democracia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/5623d53fe2e579d825b1679734abcc44\",\"name\":\"Forbes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g\",\"caption\":\"Forbes\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/forbes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMLO dice que INE fue creado para impedir la democracia - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/","og_locale":"es_MX","og_type":"article","og_title":"AMLO dice que INE fue creado para impedir la democracia - Fuentes Fidedignas","og_description":"L\u00f3pez Obrador pidi\u00f3 que se denuncien la entrega de despensas, dinero o amenazas que se hagan para obtener el voto a favor de un candidato. Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador critic\u00f3 al Instituto Nacional Electoral (INE), dijo que el organismo no investiga la supuesta compra de votos por parte del candidato [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-05-06T15:31:34+00:00","article_modified_time":"2021-05-06T15:31:36+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/amlo-abr-29-640x360-1.jpg","type":"image\/jpeg"}],"author":"Forbes","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Forbes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/"},"author":{"name":"Forbes","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/5623d53fe2e579d825b1679734abcc44"},"headline":"AMLO dice que INE fue creado para impedir la democracia","datePublished":"2021-05-06T15:31:34+00:00","dateModified":"2021-05-06T15:31:36+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/"},"wordCount":359,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/amlo-abr-29-640x360-1.jpg","keywords":["AMLO","Andr\u00e9s Manuel L\u00f3pez Obrador","Elecciones 2021","INE","Instituto Nacional Electoral"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/","name":"AMLO dice que INE fue creado para impedir la democracia - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/amlo-abr-29-640x360-1.jpg","datePublished":"2021-05-06T15:31:34+00:00","dateModified":"2021-05-06T15:31:36+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/amlo-abr-29-640x360-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/amlo-abr-29-640x360-1.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/06\/amlo-dice-que-ine-fue-creado-para-impedir-la-democracia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"AMLO dice que INE fue creado para impedir la democracia"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/5623d53fe2e579d825b1679734abcc44","name":"Forbes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g","caption":"Forbes"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/forbes\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1222\/revisions"}],"predecessor-version":[{"id":1224,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1222\/revisions\/1224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1223"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}