{"id":117083,"date":"2025-09-10T15:58:27","date_gmt":"2025-09-10T22:58:27","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=117083"},"modified":"2025-09-10T15:58:55","modified_gmt":"2025-09-10T22:58:55","slug":"explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/","title":{"rendered":"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>De acuerdo con informaci\u00f3n del Gobierno de CDMX, 19 de los heridos se encuentran en estado grave. Todos fueron trasladados a hospitales para su atenci\u00f3n m\u00e9dica.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La explosi\u00f3n de una pipa de gas en el Puente de la Concordia, en los l\u00edmites de la Ciudad de M\u00e9xico y el Estado de M\u00e9xico, dej\u00f3 57 lesionados y provoc\u00f3 una amplia movilizaci\u00f3n de los cuerpos de emergencia en la zona oriente de la capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con los primeros reportes, la unidad transportaba m\u00e1s de 40,000 litros de gas LP y circulaba en la incorporaci\u00f3n de la Calzada Ignacio Zaragoza hacia la carretera federal M\u00e9xico-Puebla, en direcci\u00f3n a Los Reyes La Paz, Estado de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jefa de Gobierno, Clara Brugada, inform\u00f3 que de manera preliminar se tiene un registro de 57 personas heridas. De ellas, 12 fueron trasladadas al Hospital Regional Juan Ram\u00f3n de la Fuente en Iztapalapa; nueve al Hospital Emiliano Zapata, tambi\u00e9n en Iztapalapa; y 15 al Hospital General 53 en Los Reyes La Paz, Estado de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros 15 lesionados fueron ingresados al Hospital ISSSTE Morelos e Iztapalapa; uno al ISSSTE Zaragoza; cinco al Instituto Nacional de Rehabilitaci\u00f3n y uno m\u00e1s al Hospital Rub\u00e9n Le\u00f1ero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el director general del ISSSTE, Mart\u00ed Batres, se\u00f1al\u00f3 a trav\u00e9s de redes sociales que toda persona que requiera atenci\u00f3n hospitalaria a causa de la explosi\u00f3n en Zaragoza podr\u00e1 ser atendida en cualquier unidad de la instituci\u00f3n, a\u00fan sin ser derechohabiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una fuga de gas habr\u00eda generado un chispazo que primero desat\u00f3 el incendio de la pipa.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"es\" dir=\"ltr\">14:52 <a href=\"https:\/\/twitter.com\/hashtag\/Precauci%C3%B3nVial?src=hash&amp;ref_src=twsrc%5Etfw\">#Precauci\u00f3nVial<\/a> | Servicios de emergencia acuden a la Calz. Ignacio Zaragoza a la altura del Puente de la Concordia al Poniente por incendio, oficiales de <a href=\"https:\/\/twitter.com\/hashtag\/Tr%C3%A1nsito?src=hash&amp;ref_src=twsrc%5Etfw\">#Tr\u00e1nsito<\/a> de la <a href=\"https:\/\/twitter.com\/hashtag\/SSC?src=hash&amp;ref_src=twsrc%5Etfw\">#SSC<\/a> realizan cortes a la circulaci\u00f3n en la zona para agilizar el arribo de las m\u00e9dicas y bomberos,\u2026 <a href=\"https:\/\/t.co\/bJSkB7v62g\">pic.twitter.com\/bJSkB7v62g<\/a><\/p>&mdash; OVIAL_SSCCDMX (@OVIALCDMX) <a href=\"https:\/\/twitter.com\/OVIALCDMX\/status\/1965881092654739845?ref_src=twsrc%5Etfw\">September 10, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">Minutos m\u00e1s tarde, el fuego alcanz\u00f3 la cisterna y provoc\u00f3 una fuerte explosi\u00f3n, que dej\u00f3 varios veh\u00edculos incendiados, tanto en la parte baja como en la superior del Puente de la Concordia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por la emergencia, la Secretar\u00eda de Movilidad de la Ciudad de M\u00e9xico inform\u00f3 la suspensi\u00f3n temporal del servicio en las estaciones Santa Martha de la L\u00ednea A del Metro; el Troleb\u00fas Elevado; el Troleb\u00fas de Santa Martha a Constituci\u00f3n de 1917; la ruta Chalco\u2013Santa Martha y la L\u00ednea 2 del Cableb\u00fas.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"es\" dir=\"ltr\">Polic\u00edas de la Subsecretar\u00eda de Control de <a href=\"https:\/\/twitter.com\/hashtag\/Tr%C3%A1nsito?src=hash&amp;ref_src=twsrc%5Etfw\">#Tr\u00e1nsito<\/a> y de Operaci\u00f3n Policial de la <a href=\"https:\/\/twitter.com\/hashtag\/SSC?src=hash&amp;ref_src=twsrc%5Etfw\">#SSC<\/a>, contin\u00faan con las labores de resguardo en las inmediaciones del Puente de la Concordia, as\u00ed como con el retiro de los veh\u00edculos involucrados para evitar otros incidentes en la zona. <a href=\"https:\/\/t.co\/g6aLz611jA\">pic.twitter.com\/g6aLz611jA<\/a><\/p>&mdash; OVIAL_SSCCDMX (@OVIALCDMX) <a href=\"https:\/\/twitter.com\/OVIALCDMX\/status\/1965892210974724302?ref_src=twsrc%5Etfw\">September 10, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">Myriam Urz\u00faa, secretaria de Protecci\u00f3n Civil de la Ciudad de M\u00e9xico, inform\u00f3 en conferencia de prensa que el incendio se origin\u00f3 tras la volcadura de una pipa de gas LP con una carga de 49,500 litros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El saldo preliminar tambi\u00e9n incluye 18 veh\u00edculos da\u00f1ados y una motocicleta incendiada.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"es\" dir=\"ltr\">En el sitio, Polic\u00edas de la <a href=\"https:\/\/twitter.com\/hashtag\/SSC?src=hash&amp;ref_src=twsrc%5Etfw\">#SSC<\/a> y <a href=\"https:\/\/twitter.com\/hashtag\/Bomberos?src=hash&amp;ref_src=twsrc%5Etfw\">#Bomberos<\/a> ya realizan las acciones para apagar el fuego, mientras que en los alrededores contin\u00faa el cerco y la evacuaci\u00f3n de personas, los desv\u00edos a la circulaci\u00f3n vehicular. Se mantiene cerrada la circulaci\u00f3n en ambos sentidos de la autopista\u2026 <a href=\"https:\/\/t.co\/VN88Hyl8wZ\">pic.twitter.com\/VN88Hyl8wZ<\/a><\/p>&mdash; OVIAL_SSCCDMX (@OVIALCDMX) <a href=\"https:\/\/twitter.com\/OVIALCDMX\/status\/1965891331030421651?ref_src=twsrc%5Etfw\">September 10, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>-Informaci\u00f3n en desarrollo.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con informaci\u00f3n del Gobierno de CDMX, 19 de los heridos se encuentran en estado grave. Todos fueron trasladados a hospitales para su atenci\u00f3n m\u00e9dica. La explosi\u00f3n de una pipa de gas en el Puente de la Concordia, en los l\u00edmites de la Ciudad de M\u00e9xico y el Estado de M\u00e9xico, dej\u00f3 57 lesionados [&hellip;]<\/p>\n","protected":false},"author":89,"featured_media":117084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-117083","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"De acuerdo con informaci\u00f3n del Gobierno de CDMX, 19 de los heridos se encuentran en estado grave. Todos fueron trasladados a hospitales para su atenci\u00f3n m\u00e9dica. La explosi\u00f3n de una pipa de gas en el Puente de la Concordia, en los l\u00edmites de la Ciudad de M\u00e9xico y el Estado de M\u00e9xico, dej\u00f3 57 lesionados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-10T22:58:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T22:58:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/09\/explosion_pipa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expansi\u00f3n \u00a0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expansi\u00f3n \u00a0\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/\"},\"author\":{\"name\":\"Expansi\u00f3n \u00a0\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/927b77c3bc41c5093b47873a3f0c99ae\"},\"headline\":\"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados\",\"datePublished\":\"2025-09-10T22:58:27+00:00\",\"dateModified\":\"2025-09-10T22:58:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/\"},\"wordCount\":624,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/explosion_pipa.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/\",\"name\":\"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/explosion_pipa.jpg\",\"datePublished\":\"2025-09-10T22:58:27+00:00\",\"dateModified\":\"2025-09-10T22:58:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/explosion_pipa.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/explosion_pipa.jpg\",\"width\":500,\"height\":281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/09\\\/10\\\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/927b77c3bc41c5093b47873a3f0c99ae\",\"name\":\"Expansi\u00f3n \u00a0\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g\",\"caption\":\"Expansi\u00f3n \u00a0\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/expansion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/","og_locale":"es_MX","og_type":"article","og_title":"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados - Fuentes Fidedignas","og_description":"De acuerdo con informaci\u00f3n del Gobierno de CDMX, 19 de los heridos se encuentran en estado grave. Todos fueron trasladados a hospitales para su atenci\u00f3n m\u00e9dica. La explosi\u00f3n de una pipa de gas en el Puente de la Concordia, en los l\u00edmites de la Ciudad de M\u00e9xico y el Estado de M\u00e9xico, dej\u00f3 57 lesionados [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2025-09-10T22:58:27+00:00","article_modified_time":"2025-09-10T22:58:55+00:00","og_image":[{"width":500,"height":281,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/09\/explosion_pipa.jpg","type":"image\/jpeg"}],"author":"Expansi\u00f3n \u00a0","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Expansi\u00f3n \u00a0","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/"},"author":{"name":"Expansi\u00f3n \u00a0","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/927b77c3bc41c5093b47873a3f0c99ae"},"headline":"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados","datePublished":"2025-09-10T22:58:27+00:00","dateModified":"2025-09-10T22:58:55+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/"},"wordCount":624,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/09\/explosion_pipa.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/","name":"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/09\/explosion_pipa.jpg","datePublished":"2025-09-10T22:58:27+00:00","dateModified":"2025-09-10T22:58:55+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/09\/explosion_pipa.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/09\/explosion_pipa.jpg","width":500,"height":281},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/09\/10\/explosion-de-pipa-de-gas-en-puente-de-la-concordia-deja-57-lesionados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Explosi\u00f3n de pipa de gas en Puente de la Concordia deja 57 lesionados"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/927b77c3bc41c5093b47873a3f0c99ae","name":"Expansi\u00f3n \u00a0","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g","caption":"Expansi\u00f3n \u00a0"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/expansion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/117083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=117083"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/117083\/revisions"}],"predecessor-version":[{"id":117085,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/117083\/revisions\/117085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/117084"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=117083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=117083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=117083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}