{"id":111365,"date":"2025-06-24T12:26:00","date_gmt":"2025-06-24T19:26:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=111365"},"modified":"2025-06-24T12:25:32","modified_gmt":"2025-06-24T19:25:32","slug":"se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/","title":{"rendered":"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Andrea se form\u00f3 inusualmente m\u00e1s al norte y al este en comparaci\u00f3n con tormentas con nombre anteriores, sobre una zona de aguas oce\u00e1nicas m\u00e1s c\u00e1lidas de lo normal.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una zona de tiempo tormentoso en el oc\u00e9ano Atl\u00e1ntico, entre las Bermudas y las Azores, se convirti\u00f3 en la tormenta tropical Andrea la ma\u00f1ana de este martes, la primera con nombre de la temporada de huracanes 2025 del Atl\u00e1ntico, seg\u00fan el Centro Nacional de Huracanes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea no representa una amenaza para tierra firme. La tormenta se encuentra aproximadamente a 1.930 kil\u00f3metros de las Azores, o a unos 2250 kil\u00f3metros al este de la costa este de EE.UU., con vientos m\u00e1ximos sostenidos de 64 km\/h a las 11:00 a. m. hora de Miami de este martes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se pronostica que la tormenta se desplazar\u00e1 hacia el noreste a 27 km\/h y no representa una amenaza para tierra firme. No hay alertas costeras vigentes, y se prev\u00e9 que Andrea se disipe el mi\u00e9rcoles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAndrea ser\u00e1 una tormenta tropical de corta duraci\u00f3n\u201d, declar\u00f3 el Centro Nacional de Huracanes en un foro de pron\u00f3sticos en l\u00ednea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea se form\u00f3 inusualmente m\u00e1s al norte y al este en comparaci\u00f3n con tormentas con nombre anteriores, sobre una zona de aguas oce\u00e1nicas m\u00e1s c\u00e1lidas de lo normal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La temporada de huracanes del Atl\u00e1ntico de 2025 ha tenido un comienzo lento, con la primera tormenta con nombre form\u00e1ndose, en promedio, alrededor del 20 de junio. Los principales factores que impiden la formaci\u00f3n de tormentas en el Atl\u00e1ntico actualmente son el viento, las temperaturas del oc\u00e9ano y, en particular, el polvo sahariano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las tormentas tropicales necesitan aire c\u00e1lido y h\u00famedo para formarse, as\u00ed como aguas oce\u00e1nicas c\u00e1lidas para generar energ\u00eda. El polvo sahariano tiende a inhibir la formaci\u00f3n de tormentas al transportar aire seco y reflejar la luz solar entrante, lo que provoca una disminuci\u00f3n de la temperatura superficial del mar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar del comienzo m\u00e1s lento, especialmente en comparaci\u00f3n con temporadas recientes inusualmente activas, se espera que la temporada de huracanes del Atl\u00e1ntico de 2025 sea superior a la media.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pron\u00f3stico estacional de la NOAA prev\u00e9 hasta 10 huracanes, cuando una temporada promedio registrar\u00eda siete. Se proyecta que entre tres y cinco de estas tormentas ser\u00e1n huracanes mayores de categor\u00eda 3 o superior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se cree que el cambio clim\u00e1tico est\u00e9 incrementando el n\u00famero de tormentas del Atl\u00e1ntico cada temporada, pero s\u00ed est\u00e1 haciendo que las que se forman produzcan lluvias m\u00e1s intensas y experimenten episodios m\u00e1s frecuentes y extremos de r\u00e1pida intensificaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andrea se form\u00f3 inusualmente m\u00e1s al norte y al este en comparaci\u00f3n con tormentas con nombre anteriores, sobre una zona de aguas oce\u00e1nicas m\u00e1s c\u00e1lidas de lo normal. Una zona de tiempo tormentoso en el oc\u00e9ano Atl\u00e1ntico, entre las Bermudas y las Azores, se convirti\u00f3 en la tormenta tropical Andrea la ma\u00f1ana de este martes, [&hellip;]<\/p>\n","protected":false},"author":69,"featured_media":111366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-111365","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Andrea se form\u00f3 inusualmente m\u00e1s al norte y al este en comparaci\u00f3n con tormentas con nombre anteriores, sobre una zona de aguas oce\u00e1nicas m\u00e1s c\u00e1lidas de lo normal. Una zona de tiempo tormentoso en el oc\u00e9ano Atl\u00e1ntico, entre las Bermudas y las Azores, se convirti\u00f3 en la tormenta tropical Andrea la ma\u00f1ana de este martes, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-24T19:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/06\/tormenta-tropical-andrea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CNN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CNN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/\"},\"author\":{\"name\":\"CNN\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/c8880efbe84cd7e0991e9a2bbe8394f4\"},\"headline\":\"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico\",\"datePublished\":\"2025-06-24T19:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/\"},\"wordCount\":465,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/tormenta-tropical-andrea.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/\",\"name\":\"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/tormenta-tropical-andrea.jpg\",\"datePublished\":\"2025-06-24T19:26:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/tormenta-tropical-andrea.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/tormenta-tropical-andrea.jpg\",\"width\":600,\"height\":337},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/06\\\/24\\\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/c8880efbe84cd7e0991e9a2bbe8394f4\",\"name\":\"CNN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01dae67c419c360a2e77032cdc95d8b45e5626805917f1b6720a01f56beef992?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01dae67c419c360a2e77032cdc95d8b45e5626805917f1b6720a01f56beef992?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01dae67c419c360a2e77032cdc95d8b45e5626805917f1b6720a01f56beef992?s=96&d=mm&r=g\",\"caption\":\"CNN\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/cnn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/","og_locale":"es_MX","og_type":"article","og_title":"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico - Fuentes Fidedignas","og_description":"Andrea se form\u00f3 inusualmente m\u00e1s al norte y al este en comparaci\u00f3n con tormentas con nombre anteriores, sobre una zona de aguas oce\u00e1nicas m\u00e1s c\u00e1lidas de lo normal. Una zona de tiempo tormentoso en el oc\u00e9ano Atl\u00e1ntico, entre las Bermudas y las Azores, se convirti\u00f3 en la tormenta tropical Andrea la ma\u00f1ana de este martes, [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2025-06-24T19:26:00+00:00","og_image":[{"width":600,"height":337,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/06\/tormenta-tropical-andrea.jpg","type":"image\/jpeg"}],"author":"CNN","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"CNN","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/"},"author":{"name":"CNN","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/c8880efbe84cd7e0991e9a2bbe8394f4"},"headline":"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico","datePublished":"2025-06-24T19:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/"},"wordCount":465,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/06\/tormenta-tropical-andrea.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/","name":"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/06\/tormenta-tropical-andrea.jpg","datePublished":"2025-06-24T19:26:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/06\/tormenta-tropical-andrea.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/06\/tormenta-tropical-andrea.jpg","width":600,"height":337},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/06\/24\/se-forma-la-tormenta-tropical-andrea-en-el-oceano-atlantico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Se forma la tormenta tropical Andrea en el oc\u00e9ano Atl\u00e1ntico"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/c8880efbe84cd7e0991e9a2bbe8394f4","name":"CNN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/01dae67c419c360a2e77032cdc95d8b45e5626805917f1b6720a01f56beef992?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01dae67c419c360a2e77032cdc95d8b45e5626805917f1b6720a01f56beef992?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01dae67c419c360a2e77032cdc95d8b45e5626805917f1b6720a01f56beef992?s=96&d=mm&r=g","caption":"CNN"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/cnn\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/111365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=111365"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/111365\/revisions"}],"predecessor-version":[{"id":111367,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/111365\/revisions\/111367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/111366"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=111365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=111365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=111365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}