{"id":104020,"date":"2025-03-15T13:19:31","date_gmt":"2025-03-15T20:19:31","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=104020"},"modified":"2025-03-15T13:19:31","modified_gmt":"2025-03-15T20:19:31","slug":"en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/","title":{"rendered":"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Navolato, Sinaloa.- Personal de la Secretar\u00eda de la Defensa Nacional, en coordinaci\u00f3n con la Guardia Nacional, la Secretar\u00eda de Marina, la Fiscal\u00eda General de la Rep\u00fablica, la Fiscal\u00eda General del Estado y la Secretar\u00eda de Seguridad P\u00fablica, aseguraron un veh\u00edculo y, en su interior, presuntas drogas, un cargador, cartuchos, puntas de acero y una placa bal\u00edstica en Villa Ju\u00e1rez, Navolato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante reconocimientos terrestres en la sindicatura de Villa Ju\u00e1rez, del municipio de Navolato, personal militar localiz\u00f3 una camioneta Tahoe, marca Chevrolet, con reporte de robo. En el interior del veh\u00edculo se localizaron dosis de presuntas drogas conocidas como cristal y marihuana, adem\u00e1s de un cargador para AK-47 calibre 7.62 x 39 mm abastecido con 13 cartuchos del mismo calibre, estrellas met\u00e1licas y una placa bal\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo lo anterior fue asegurado y puesto a disposici\u00f3n del Ministerio P\u00fablico Federal para realizar las indagaciones correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se invita a marcar oportunamente al 911 para cualquier emergencia y al 089 para realizar denuncias an\u00f3nimas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Navolato, Sinaloa.- Personal de la Secretar\u00eda de la Defensa Nacional, en coordinaci\u00f3n con la Guardia Nacional, la Secretar\u00eda de Marina, la Fiscal\u00eda General de la Rep\u00fablica, la Fiscal\u00eda General del Estado y la Secretar\u00eda de Seguridad P\u00fablica, aseguraron un veh\u00edculo y, en su interior, presuntas drogas, un cargador, cartuchos, puntas de acero y una placa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":104019,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-104020","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Navolato, Sinaloa.- Personal de la Secretar\u00eda de la Defensa Nacional, en coordinaci\u00f3n con la Guardia Nacional, la Secretar\u00eda de Marina, la Fiscal\u00eda General de la Rep\u00fablica, la Fiscal\u00eda General del Estado y la Secretar\u00eda de Seguridad P\u00fablica, aseguraron un veh\u00edculo y, en su interior, presuntas drogas, un cargador, cartuchos, puntas de acero y una placa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T20:19:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"963\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento\",\"datePublished\":\"2025-03-15T20:19:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/\"},\"wordCount\":189,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg\",\"articleSection\":[\"NOTA PRINCIPAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/\",\"name\":\"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg\",\"datePublished\":\"2025-03-15T20:19:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg\",\"width\":1440,\"height\":963},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/15\\\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/","og_locale":"es_MX","og_type":"article","og_title":"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento - Fuentes Fidedignas","og_description":"Navolato, Sinaloa.- Personal de la Secretar\u00eda de la Defensa Nacional, en coordinaci\u00f3n con la Guardia Nacional, la Secretar\u00eda de Marina, la Fiscal\u00eda General de la Rep\u00fablica, la Fiscal\u00eda General del Estado y la Secretar\u00eda de Seguridad P\u00fablica, aseguraron un veh\u00edculo y, en su interior, presuntas drogas, un cargador, cartuchos, puntas de acero y una placa [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2025-03-15T20:19:31+00:00","og_image":[{"width":1440,"height":963,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento","datePublished":"2025-03-15T20:19:31+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/"},"wordCount":189,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg","articleSection":["NOTA PRINCIPAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/","name":"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg","datePublished":"2025-03-15T20:19:31+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/4e6fe519-6db7-4ec8-b9c4-62dc3522437b-1.jpg","width":1440,"height":963},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/15\/en-villa-juarez-aseguran-vehiculo-con-reporte-de-robo-drogas-y-armamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"En Villa Ju\u00e1rez, aseguran veh\u00edculo con reporte de robo, drogas y armamento"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/104020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=104020"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/104020\/revisions"}],"predecessor-version":[{"id":104021,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/104020\/revisions\/104021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/104019"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=104020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=104020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=104020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}