{"id":103583,"date":"2025-03-11T07:36:05","date_gmt":"2025-03-11T14:36:05","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=103583"},"modified":"2025-03-11T07:36:10","modified_gmt":"2025-03-11T14:36:10","slug":"la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/","title":{"rendered":"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>El Vaticano inform\u00f3 que el papa Francisco a\u00fan requerir\u00e1 estar en terapia m\u00e9dica farmacol\u00f3gica algunos d\u00edas m\u00e1s.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El papa Francisco, que lleva m\u00e1s de tres semanas hospitalizado por una neumon\u00eda, est\u00e1 mejor y sus avances se han \u201cconsolidado\u201d, por lo que los m\u00e9dicos decidieron el lunes que su pron\u00f3stico deja de ser reservado y estimaron que tendr\u00e1 que quedarse \u201calgunos d\u00edas m\u00e1s\u201d en el hospital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas mejoras registradas en los d\u00edas anteriores se han consolidado a\u00fan m\u00e1s, como confirman los an\u00e1lisis de sangre, la objetividad cl\u00ednica y la buena respuesta a la terapia farmacol\u00f3gica. Por estas razones, los m\u00e9dicos han decidido hoy disolver el pron\u00f3stico\u201d, indic\u00f3 el Vaticano en el bolet\u00edn m\u00e9dico del lunes por la noche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estado cl\u00ednico del jesuita de 88 a\u00f1os \u201csigue estable\u201d pero \u201cdada la complejidad del cuadro cl\u00ednico y el importante cuadro infeccioso presentado en el momento del ingreso, ser\u00e1 necesario continuar la terapia m\u00e9dica farmacol\u00f3gica en r\u00e9gimen hospitalario durante algunos d\u00edas m\u00e1s\u201d, agreg\u00f3 el comunicado, dando a entender que el pont\u00edfice argentino podr\u00eda dejar el hospital en los pr\u00f3ximos d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Horas antes de anunciarse que el pron\u00f3stico dejaba de ser reservado, una fuente vaticana afirm\u00f3 que era \u201cdemasiado pronto para hablar de su regreso a Santa Marta\u201d, la residencia donde vive en la Santa Sede.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El l\u00edder espiritual de los cat\u00f3licos del mundo ingres\u00f3 en el hospital Gemelli de Roma el 14 de febrero donde ha sufrido varias crisis respiratorias, la \u00faltima hace siete d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Vaticano inform\u00f3 en la ma\u00f1ana del lunes que Francisco hab\u00eda pasado \u201cuna noche tranquila\u201d en su suite en la d\u00e9cima planta del hospital y que iba a pasar la jornada haciendo terapia f\u00edsica y respiratoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como en ma\u00f1anas anteriores, el lunes tambi\u00e9n le cambiaron la m\u00e1scara de ox\u00edgeno que usa todas las noches por una c\u00e1nula nasal de alto flujo, un soporte m\u00e1s ligero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su estancia en el hospital, el papa ha estado trabajando de manera intermitente y siguiendo las noticias siempre que ha sido posible, incluidas las inundaciones que han afectado a su pa\u00eds natal, Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El lunes, el pont\u00edfice expres\u00f3 su dolor en un telegrama en recuerdo a las v\u00edctimas: \u201cApenado al enterarme sobre el desastre natural que est\u00e1 afectando a la regi\u00f3n de Bah\u00eda Blanca, y que ha ocasionado tantas v\u00edctimas y da\u00f1os materiales\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOfrezco fervientes sufragios por el eterno descanso de los fallecidos. Asimismo quiero hacer sentir mi cercan\u00eda espiritual a toda su poblaci\u00f3n\u201d, escribi\u00f3 en espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El temporal que azot\u00f3 el viernes esa ciudad argentina ha dejado al menos 16 muertos, un centenar de desaparecidos y p\u00e9rdidas millonarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Papa Francisco env\u00eda agradecimiento a los m\u00e9dicos<\/strong><br>El papa Francisco ha sufrido varios problemas de salud en los \u00faltimos a\u00f1os, incluyendo una operaci\u00f3n de colon en 2021 y otra para tratarle una hernia en 2023. Pero esta es su estancia m\u00e1s larga y grave en el hospital desde que empez\u00f3 su papado, en 2013.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otras ocasiones Francisco sali\u00f3 al balc\u00f3n del hospital Gemelli para la oraci\u00f3n dominical del \u00c1ngelus pero esta vez lleva cuatro semanas envi\u00e1ndolo por escrito en lugar de pronunciarlo desde el Palacio Apost\u00f3lico, situado en la plaza de San Pedro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo al mediod\u00eda, el pont\u00edfice dio las gracias en un mensaje al personal m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHermanos y hermanas, en mi prolongada hospitalizaci\u00f3n, tambi\u00e9n yo experimento el esmero en el servicio y la ternura en el cuidado, especialmente por parte de los m\u00e9dicos y de los operadores sanitarios, a quienes doy las gracias de coraz\u00f3n\u201d, escribi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El papa no ha sido visto en persona desde que fue ingresado en el hospital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su \u00fanico mensaje directo fue un audio publicado el jueves en espa\u00f1ol en el que, con voz cansada y respiraci\u00f3n entrecortada, agradeci\u00f3 las oraciones por su pronta recuperaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora, los m\u00e9dicos no se hab\u00edan pronunciado sobre cu\u00e1nto durar\u00e1 el ingreso ni tampoco sobre el tiempo que podr\u00eda tomar la convalecencia de Jorge Bergoglio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa esperanza de que el papa se recupere est\u00e1 siempre presente en nosotros\u201d, dijo el domingo a la AFP Matteo Peafrini, un voluntario de Protecci\u00f3n Civil de la regi\u00f3n de Lombard\u00eda que participaba en una multitudinaria misa en el Vaticano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Vaticano inform\u00f3 que el papa Francisco a\u00fan requerir\u00e1 estar en terapia m\u00e9dica farmacol\u00f3gica algunos d\u00edas m\u00e1s. El papa Francisco, que lleva m\u00e1s de tres semanas hospitalizado por una neumon\u00eda, est\u00e1 mejor y sus avances se han \u201cconsolidado\u201d, por lo que los m\u00e9dicos decidieron el lunes que su pron\u00f3stico deja de ser reservado y estimaron [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":103097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-103583","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El Vaticano inform\u00f3 que el papa Francisco a\u00fan requerir\u00e1 estar en terapia m\u00e9dica farmacol\u00f3gica algunos d\u00edas m\u00e1s. El papa Francisco, que lleva m\u00e1s de tres semanas hospitalizado por una neumon\u00eda, est\u00e1 mejor y sus avances se han \u201cconsolidado\u201d, por lo que los m\u00e9dicos decidieron el lunes que su pron\u00f3stico deja de ser reservado y estimaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T14:36:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T14:36:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/papa_Francisco-enfermo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Animal Politico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Animal Politico\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/\"},\"author\":{\"name\":\"Animal Politico\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/46034ce436b72de8f0cb35d8168f96dc\"},\"headline\":\"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n\",\"datePublished\":\"2025-03-11T14:36:05+00:00\",\"dateModified\":\"2025-03-11T14:36:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/\"},\"wordCount\":779,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/papa_Francisco-enfermo.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/\",\"name\":\"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/papa_Francisco-enfermo.jpg\",\"datePublished\":\"2025-03-11T14:36:05+00:00\",\"dateModified\":\"2025-03-11T14:36:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/papa_Francisco-enfermo.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/papa_Francisco-enfermo.jpg\",\"width\":600,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/03\\\/11\\\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/46034ce436b72de8f0cb35d8168f96dc\",\"name\":\"Animal Politico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c8b42abba0c23cdccccfc885a8cfe2e0faaa5e86c5b918524de5cb33c9b1e8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c8b42abba0c23cdccccfc885a8cfe2e0faaa5e86c5b918524de5cb33c9b1e8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c8b42abba0c23cdccccfc885a8cfe2e0faaa5e86c5b918524de5cb33c9b1e8a?s=96&d=mm&r=g\",\"caption\":\"Animal Politico\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/animal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/","og_locale":"es_MX","og_type":"article","og_title":"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n - Fuentes Fidedignas","og_description":"El Vaticano inform\u00f3 que el papa Francisco a\u00fan requerir\u00e1 estar en terapia m\u00e9dica farmacol\u00f3gica algunos d\u00edas m\u00e1s. El papa Francisco, que lleva m\u00e1s de tres semanas hospitalizado por una neumon\u00eda, est\u00e1 mejor y sus avances se han \u201cconsolidado\u201d, por lo que los m\u00e9dicos decidieron el lunes que su pron\u00f3stico deja de ser reservado y estimaron [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2025-03-11T14:36:05+00:00","article_modified_time":"2025-03-11T14:36:10+00:00","og_image":[{"width":600,"height":375,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/papa_Francisco-enfermo.jpg","type":"image\/jpeg"}],"author":"Animal Politico","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Animal Politico","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/"},"author":{"name":"Animal Politico","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/46034ce436b72de8f0cb35d8168f96dc"},"headline":"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n","datePublished":"2025-03-11T14:36:05+00:00","dateModified":"2025-03-11T14:36:10+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/"},"wordCount":779,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/papa_Francisco-enfermo.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/","name":"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/papa_Francisco-enfermo.jpg","datePublished":"2025-03-11T14:36:05+00:00","dateModified":"2025-03-11T14:36:10+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/papa_Francisco-enfermo.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/03\/papa_Francisco-enfermo.jpg","width":600,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/03\/11\/la-salud-del-papa-francisco-mejora-y-el-vaticano-contempla-el-final-de-su-hospitalizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"La salud del papa Francisco mejora y el Vaticano contempla el final de su hospitalizaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/46034ce436b72de8f0cb35d8168f96dc","name":"Animal Politico","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5c8b42abba0c23cdccccfc885a8cfe2e0faaa5e86c5b918524de5cb33c9b1e8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c8b42abba0c23cdccccfc885a8cfe2e0faaa5e86c5b918524de5cb33c9b1e8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c8b42abba0c23cdccccfc885a8cfe2e0faaa5e86c5b918524de5cb33c9b1e8a?s=96&d=mm&r=g","caption":"Animal Politico"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/animal\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/103583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=103583"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/103583\/revisions"}],"predecessor-version":[{"id":103584,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/103583\/revisions\/103584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/103097"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=103583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=103583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=103583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}