{"id":101014,"date":"2025-02-05T19:50:50","date_gmt":"2025-02-06T02:50:50","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=101014"},"modified":"2025-02-05T19:50:53","modified_gmt":"2025-02-06T02:50:53","slug":"republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/","title":{"rendered":"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>La novena de Rep\u00fablica Dominicana se impuso por 5-4 en extra innings sobre Venezuela y avanz\u00f3 a la final de la Serie del Caribe 2025<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La novena de Rep\u00fablica Dominicana avanz\u00f3 a la final de la Serie del Caribe-2025 al vencer 5-4 a Venezuela con un carrera impulsada por S\u00f3crates Brito en la und\u00e9cima entrada este mi\u00e9rcoles, en partido de semifinales jugado en el estadio Nido del \u00c1guilas, en Mexicali, M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La novena dominicana se adelant\u00f3 1-0 en la apertura de la primera entrada. Robinson Can\u00f3 peg\u00f3 un doblete al jard\u00edn izquierdo y remolc\u00f3 a Brito.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1Elevado de sacrificio y RD se adelanta 4-3! \ud83c\udde9\ud83c\uddf4\ud83d\ude2e\u200d\ud83d\udca8<a href=\"https:\/\/twitter.com\/hashtag\/SDCMexicali2025?src=hash&amp;ref_src=twsrc%5Etfw\">#SDCMexicali2025<\/a> <a href=\"https:\/\/t.co\/b10X7Ygn7X\">pic.twitter.com\/b10X7Ygn7X<\/a><\/p>&mdash; Serie del Caribe (@beisboldecaribe) <a href=\"https:\/\/twitter.com\/beisboldecaribe\/status\/1887311851220050088?ref_src=twsrc%5Etfw\">February 6, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Junior Lake anot\u00f3 la del 2-0 en la tercera ante una falla entre el campocorto Eduardo Garc\u00eda y el segunda base Ildemaro Vargas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El conjunto venezolano meti\u00f3 presi\u00f3n en la s\u00e9ptima entrada cuando Hern\u00e1n P\u00e9rez dio un toque de sacrificio para que Jos\u00e9 Rond\u00f3n timbrara el 2-1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La escuadra quisqueyana recuper\u00f3 el aliento en la octava con la 3-1 que Gustavo N\u00fa\u00f1ez anot\u00f3 de pisa y corre tras un elevado de Brito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venezuela puso el suspenso en el desenlace del octavo episodio. La casa se le llen\u00f3 de Cardenales al relevista Fernando Abad; Ildemaro Vargas -con sencillo de Rangel Ravelo- y Gorkys Hern\u00e1ndez -con elevado de sacrificio de Rond\u00f3n- igualaron la pizarra 3-3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si no hubo m\u00e1s carreras para el cuadro llanero en esa ofensiva fue porque Alexi Amarista dud\u00f3 en el recorrido y fue puesto out en tercera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La novena entrada termin\u00f3 con el pitcheo de Ulises Joaqu\u00edn, quien con apuros dej\u00f3 a dos rivales en las almohadillas. Y as\u00ed el partido se extendi\u00f3 a extra innings.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Leones recuperaron la ventaja en la parte alta de la d\u00e9cima entrada; Francisco Mej\u00eda anot\u00f3 la 4-3 tras un elevado de sacrificio de Cristhian Adames.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ravelo remolc\u00f3 la 4-4 de los Cardenales con un sencillo que hizo pasar a Hern\u00e1ndez por la registradora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lleg\u00f3 el und\u00e9cimo cap\u00edtulo y Dominicana logr\u00f3 la carrera del triunfo. Con un doblete, Brito impuls\u00f3 a Lake a anotar la de 5-4. Ulises Joaqu\u00edn gan\u00f3 el partido con salvamento de Jimmy Cordero. Alex Scherff fue el pitcher derrotado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La novena de Rep\u00fablica Dominicana se impuso por 5-4 en extra innings sobre Venezuela y avanz\u00f3 a la final de la Serie del Caribe 2025 La novena de Rep\u00fablica Dominicana avanz\u00f3 a la final de la Serie del Caribe-2025 al vencer 5-4 a Venezuela con un carrera impulsada por S\u00f3crates Brito en la und\u00e9cima entrada [&hellip;]<\/p>\n","protected":false},"author":123,"featured_media":101015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-101014","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025 - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025 - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La novena de Rep\u00fablica Dominicana se impuso por 5-4 en extra innings sobre Venezuela y avanz\u00f3 a la final de la Serie del Caribe 2025 La novena de Rep\u00fablica Dominicana avanz\u00f3 a la final de la Serie del Caribe-2025 al vencer 5-4 a Venezuela con un carrera impulsada por S\u00f3crates Brito en la und\u00e9cima entrada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T02:50:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T02:50:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/02\/Dominicana_SC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adrenalina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrenalina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/\"},\"author\":{\"name\":\"Adrenalina\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2d428574a5422b6bceea38751c96d3d3\"},\"headline\":\"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025\",\"datePublished\":\"2025-02-06T02:50:50+00:00\",\"dateModified\":\"2025-02-06T02:50:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Dominicana_SC.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/\",\"name\":\"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025 - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Dominicana_SC.jpg\",\"datePublished\":\"2025-02-06T02:50:50+00:00\",\"dateModified\":\"2025-02-06T02:50:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Dominicana_SC.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Dominicana_SC.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/02\\\/05\\\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2d428574a5422b6bceea38751c96d3d3\",\"name\":\"Adrenalina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"caption\":\"Adrenalina\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/adrenalina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025 - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/","og_locale":"es_MX","og_type":"article","og_title":"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025 - Fuentes Fidedignas","og_description":"La novena de Rep\u00fablica Dominicana se impuso por 5-4 en extra innings sobre Venezuela y avanz\u00f3 a la final de la Serie del Caribe 2025 La novena de Rep\u00fablica Dominicana avanz\u00f3 a la final de la Serie del Caribe-2025 al vencer 5-4 a Venezuela con un carrera impulsada por S\u00f3crates Brito en la und\u00e9cima entrada [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2025-02-06T02:50:50+00:00","article_modified_time":"2025-02-06T02:50:53+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/02\/Dominicana_SC.jpg","type":"image\/jpeg"}],"author":"Adrenalina","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Adrenalina","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/"},"author":{"name":"Adrenalina","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2d428574a5422b6bceea38751c96d3d3"},"headline":"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025","datePublished":"2025-02-06T02:50:50+00:00","dateModified":"2025-02-06T02:50:53+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/02\/Dominicana_SC.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/","name":"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025 - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/02\/Dominicana_SC.jpg","datePublished":"2025-02-06T02:50:50+00:00","dateModified":"2025-02-06T02:50:53+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/02\/Dominicana_SC.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2025\/02\/Dominicana_SC.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/02\/05\/republica-dominicana-es-el-primer-finalista-de-la-serie-del-caribe-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Rep\u00fablica Dominicana es el primer finalista de la Serie del Caribe 2025"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2d428574a5422b6bceea38751c96d3d3","name":"Adrenalina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","caption":"Adrenalina"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/adrenalina\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/101014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=101014"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/101014\/revisions"}],"predecessor-version":[{"id":101016,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/101014\/revisions\/101016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/101015"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=101014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=101014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=101014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}